{"id":7294,"date":"2015-07-07T00:00:39","date_gmt":"2015-07-06T22:00:39","guid":{"rendered":"http:\/\/www.laterredufutur.com\/accueil\/?p=7294"},"modified":"2026-06-08T22:49:57","modified_gmt":"2026-06-08T20:49:57","slug":"mars-il-y-a-2-milliards-dannees","status":"publish","type":"post","link":"https:\/\/www.laterredufutur.com\/accueil\/mars-il-y-a-2-milliards-dannees\/","title":{"rendered":"Mars, il y a 2 milliards d&rsquo;ann\u00e9es"},"content":{"rendered":"<div class=\"1665f18d14f35dd9e7566e1a8ac9a3e9\" data-index=\"1\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block; text-align:center;\"\r\n     data-ad-layout=\"in-article\"\r\n     data-ad-format=\"fluid\"\r\n     data-ad-client=\"ca-pub-2860849627502538\"\r\n     data-ad-slot=\"3019501113\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p style=\"text-align: justify;\">Il semble y avoir des preuves coh\u00e9rentes et fournies par les missions r\u00e9centes des Rovers dans le pass\u00e9 d&rsquo;une plan\u00e8te Mars qui a \u00e9t\u00e9 probablement couverte par de vastes lacs, des oc\u00e9ans, ainsi que par&nbsp;une \u00e9paisse atmosph\u00e8re, tr\u00e8s semblable \u00e0 la Terre. Kevin Gill, un ing\u00e9nieur du New Hampshire a recr\u00e9\u00e9 num\u00e9riquement&nbsp;Mars comme elle aurait pu \u00eatre il y a quelques deux milliards d&rsquo;ann\u00e9es en utilisant des donn\u00e9es scientifiques et l&rsquo;imagination humaine &#8211; le r\u00e9sultat final est extr\u00eamement provocateur et&nbsp; surprenant dans le m\u00eame temps.<\/p>\n<p style=\"text-align: justify;\">Gill a utilis\u00e9 un programme open source g\u00e9ospatial pour cr\u00e9er une terre paradisiaque sur Mars, tandis que l&rsquo;atmosph\u00e8re et la v\u00e9g\u00e9tation&nbsp;ont \u00e9t\u00e9 ajout\u00e9es et bas\u00e9es sur Blue Marble de la NASA: Next Generation. Les caract\u00e9ristiques g\u00e9ologiques des couleurs&nbsp;ont \u00e9t\u00e9 \u00e9tablies sur la base des donn\u00e9es d&rsquo;\u00e9l\u00e9vations originales de cartes topographiques de la NASA. De nombreuses \u00e9tudes ont montr\u00e9 que la surface de Mars a des reliefs&nbsp;avec des deltas de rivi\u00e8res, des ravins et des c\u00f4tes oc\u00e9aniques. En outre, les r\u00e9sultats ci-dessus sugg\u00e8rent que Mars a \u00e9t\u00e9 couverte par une \u00e9paisse atmosph\u00e8re, qui est progressivement devenue de plus en plus mince en l&rsquo;absence d&rsquo;un champ magn\u00e9tique. Quant \u00e0 la v\u00e9g\u00e9tation, les nuages \u200b\u200bet d&rsquo;autres caract\u00e9ristiques ont \u00e9t\u00e9&nbsp;adapt\u00e9es, ils \u00e9taient tous bas\u00e9s sur l&rsquo;impression artistique de l&rsquo;auteur et du \u00e0 quoi&nbsp; Mars aurait pu ressembler \u00e0 son apog\u00e9e.<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0Il n&rsquo;y a aucune donn\u00e9e&nbsp;scientifique derri\u00e8re la fa\u00e7on dont je peignais, j&rsquo;ai essay\u00e9 d&rsquo;imaginer Mars \u00e0 partir de&nbsp;la Terre qui semble tenue par certaines caract\u00e9ristiques semblables ou par les effets probables du changement climatique atmosph\u00e9rique. Par exemple, je n&rsquo;imagine&nbsp;pas beaucoup de vert repris au sein de la r\u00e9gion du mont Olympe et des volcans environnants, \u00e0 la fois en raison de l&rsquo;activit\u00e9 volcanique et de la proximit\u00e9 de l&rsquo;\u00e9quateur \u00bb, dit Gill.<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0Il n&rsquo;a pas \u00e9t\u00e9 con\u00e7u comme une sc\u00e8ne scientifique exacte, et je suis s\u00fbr que certaines de mes hypoth\u00e8ses peuvent \u00eatre incorrectes\u00a0\u00bb, a poursuivi Gill. \u00abJ\u2019esp\u00e8re simplement&nbsp;d\u00e9clencher l&rsquo;imagination, donc s&rsquo;il vous pla\u00eet profitez en !\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7296\" data-permalink=\"https:\/\/www.laterredufutur.com\/accueil\/mars-il-y-a-2-milliards-dannees\/mars-water-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water1.jpg?fit=1000%2C1000&amp;ssl=1\" data-orig-size=\"1000,1000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"mars-water\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water1.jpg?fit=800%2C800&amp;ssl=1\" class=\"alignnone size-full wp-image-7296\" src=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water1.jpg?resize=1000%2C1000\" alt=\"mars-water\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water1.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water1.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water1.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water1.jpg?resize=144%2C144&amp;ssl=1 144w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water1.jpg?resize=900%2C900&amp;ssl=1 900w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">L&rsquo;image du haut montre l&rsquo;h\u00e9misph\u00e8re occidental de Mars, tandis que l&rsquo;image du bas montre l&rsquo;h\u00e9misph\u00e8re Est.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water2.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7297\" data-permalink=\"https:\/\/www.laterredufutur.com\/accueil\/mars-il-y-a-2-milliards-dannees\/mars-water-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water2.jpg?fit=1000%2C1000&amp;ssl=1\" data-orig-size=\"1000,1000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"mars-water\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water2.jpg?fit=800%2C800&amp;ssl=1\" class=\"alignnone size-full wp-image-7297\" src=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water2.jpg?resize=1000%2C1000\" alt=\"mars-water\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water2.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water2.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water2.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water2.jpg?resize=144%2C144&amp;ssl=1 144w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water2.jpg?resize=900%2C900&amp;ssl=1 900w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Comme indiqu\u00e9 ci-dessus, Mars serait certainement en mesure d\u2019abriter la vie, bien que personne n&rsquo;est actuellement en mesure de dire si&nbsp;la vie y a exist\u00e9 ou bien si elle y est toujours pr\u00e9sente .Peut-\u00eatre est-ce une id\u00e9e encore plus int\u00e9ressante, cela parait \u00eatre in\u00e9vitable lorsque vous regardez ces images saisissantes &#8211; nous, les humains peuvont-nous transformer ces superbes vues sur Mars en r\u00e9alit\u00e9 \u00e0 travers le&nbsp;Terraforming ?<\/p>\n<p>Traduction et adaptation de la Terre du Futur<\/p>\n<p>source :&nbsp;http:\/\/www.universoracionalista.org\/<\/p>\n<p class=\"bawpvc-ajax-counter\" data-id=\"7294\">(772)<\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Il semble y avoir des preuves coh\u00e9rentes et fournies par les missions r\u00e9centes des Rovers dans le pass\u00e9 d&rsquo;une plan\u00e8te&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7295,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[22],"tags":[581,4452,2059,505,507,123,2039,2381,851,308,210],"class_list":["post-7294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espace","tag-adaptation","tag-artiste","tag-dessin","tag-image","tag-imagination","tag-mars","tag-planete-mars","tag-planete-rouge","tag-simulation","tag-vie","tag-vision","wpcat-22-id"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p631RN-1TE","jetpack-related-posts":[{"id":1862,"url":"https:\/\/www.laterredufutur.com\/accueil\/et-si-la-planete-mars-avait-une-atmosphere\/","url_meta":{"origin":7294,"position":0},"title":"Et si la plan\u00e8te Mars avait une atmosph\u00e8re","author":"Admin","date":"16 mars 2014","format":false,"excerpt":"A quoi ressemblerait la plan\u00e8te Mars avec une atmosph\u00e8re ? La plan\u00e8te Mars : son \u00e9tonnante mod\u00e9lisation A partir de donn\u00e9es de la NASA, Kevin M. Gill livre des mod\u00e9lisations \u00e9tonnantes de la plan\u00e8te Mars. A quoi ressemblerait-elle dot\u00e9e d'une atmosph\u00e8re et d'oc\u00e9ans ?","rel":"","context":"Dans &quot;Espace&quot;","block_context":{"text":"Espace","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/espace\/"},"img":{"alt_text":"Mars","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2012\/11\/mars6.jpg?fit=450%2C256&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":22404,"url":"https:\/\/www.laterredufutur.com\/accueil\/les-oceans-de-mars-seraient-caches-sous-sa-surface\/","url_meta":{"origin":7294,"position":1},"title":"Les oc\u00e9ans de Mars seraient cach\u00e9s sous sa surface","author":"Admin","date":"19 avril 2021","format":false,"excerpt":"Les oc\u00e9ans de Mars pourraient ne pas avoir disparus dans l'espace. L'importante quantit\u00e9 d'eau des oc\u00e9ans de Mars a pu rester enfouie sous la cro\u00fbte de Mars selon une nouvelle \u00e9tude. Des travaux ant\u00e9rieurs ont r\u00e9v\u00e9l\u00e9 que Mars \u00e9tait autrefois suffisamment humide pour couvrir toute sa surface avec un oc\u00e9an\u2026","rel":"","context":"Dans &quot;Espace&quot;","block_context":{"text":"Espace","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/espace\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water1.jpg?fit=1000%2C1000&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water1.jpg?fit=1000%2C1000&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water1.jpg?fit=1000%2C1000&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water1.jpg?fit=1000%2C1000&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":9165,"url":"https:\/\/www.laterredufutur.com\/accueil\/la-planete-mars-serait-elle-notre-vieille-cousine\/","url_meta":{"origin":7294,"position":2},"title":"La plan\u00e8te Mars serait-elle notre vieille cousine ?","author":"Admin","date":"7 novembre 2015","format":false,"excerpt":"En dix ans, la communaut\u00e9 scientifique en a appris autant sur l'histoire de la plan\u00e8te rouge que pendant ces cinq derni\u00e8res d\u00e9cennies. Et, il y a 4 milliards d'ann\u00e9es, Mars et la Terre n'\u00e9taient peut-\u00eatre pas si diff\u00e9rentes. A quelques d\u00e9tails pr\u00e8s\u2026 De l'eau en quantit\u00e9\u2026 il y a 4\u2026","rel":"","context":"Dans &quot;Espace&quot;","block_context":{"text":"Espace","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/espace\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/11\/mars-eau-desert-avant-apres.jpg?fit=1201%2C673&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/11\/mars-eau-desert-avant-apres.jpg?fit=1201%2C673&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/11\/mars-eau-desert-avant-apres.jpg?fit=1201%2C673&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/11\/mars-eau-desert-avant-apres.jpg?fit=1201%2C673&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/11\/mars-eau-desert-avant-apres.jpg?fit=1201%2C673&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8268,"url":"https:\/\/www.laterredufutur.com\/accueil\/pourquoi-le-rechauffement-climatique-ce-nest-pas-un-probleme-pour-la-terre\/","url_meta":{"origin":7294,"position":3},"title":"Pourquoi le r\u00e9chauffement climatique, ce n&rsquo;est pas un probl\u00e8me pour la Terre","author":"Admin","date":"17 septembre 2015","format":false,"excerpt":"Pour le climatologue Gilles Ramstein, il n\u2019y a jamais eu aussi peu de CO2 dans l\u2019atmosph\u00e8re et la Terre est actuellement dans une p\u00e9riode froide. Pourtant, le scientifique n\u2019est pas un climato-sceptique. Il reconna\u00eet volontiers que, depuis quelques d\u00e9cennies, l\u2019homme perturbe l\u2019\u00e9quilibre\u2026 Mais il n\u2019est pas inquiet pour la Terre\u2026","rel":"","context":"Dans &quot;Climat&quot;","block_context":{"text":"Climat","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/climat\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/09\/glace-et-banquise.jpg?fit=1024%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/09\/glace-et-banquise.jpg?fit=1024%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/09\/glace-et-banquise.jpg?fit=1024%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/09\/glace-et-banquise.jpg?fit=1024%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":16699,"url":"https:\/\/www.laterredufutur.com\/accueil\/des-molecules-organiques-decouvertes-sur-la-planete-mars-annonce-la-nasa\/","url_meta":{"origin":7294,"position":4},"title":"Des mol\u00e9cules organiques d\u00e9couvertes sur la plan\u00e8te Mars, annonce la Nasa","author":"Admin","date":"8 juin 2018","format":false,"excerpt":"La Nasa avait soign\u00e9 ses effets\u2009: excitation et myst\u00e8re entouraient la tenue de la conf\u00e9rence de presse de ce jeudi 7 juin, consacr\u00e9e \u00e0 la plan\u00e8te Mars. Depuis le centre spatial Goddard, dans le Maryland, l\u2019agence spatiale am\u00e9ricaine a annonc\u00e9 avoir d\u00e9couvert des mol\u00e9cules organiques vieilles de plusieurs milliards d\u2019ann\u00e9es.\u2026","rel":"","context":"Dans &quot;Espace&quot;","block_context":{"text":"Espace","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/espace\/"},"img":{"alt_text":"Mars","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2012\/11\/mars2.jpg?fit=450%2C283&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14894,"url":"https:\/\/www.laterredufutur.com\/accueil\/sil-y-avait-de-la-vie-sur-terre-il-y-a-4-milliards-dannees-alors-pourquoi-pas-sur-mars\/","url_meta":{"origin":7294,"position":5},"title":"S\u2019il y avait de la vie sur Terre, il y a 4 milliards d\u2019ann\u00e9es, alors pourquoi pas sur Mars?","author":"Admin","date":"21 mars 2017","format":false,"excerpt":"Des chercheurs ont d\u00e9couvert des microfossiles au nord-est du Qu\u00e9bec qu\u2019ils datent de quelque 4 milliards d\u2019ann\u00e9es, lorsque les conditions sur Terre et sur Mars n\u2019\u00e9taient pas si \u00e9loign\u00e9es\u2026 Pr\u00e9cisons-le tout de suite : on parle de micro-organismes, des fossiles dont la longueur n\u2019exc\u00e8de pas le demi-millim\u00e8tre et le diam\u00e8tre\u2026","rel":"","context":"Dans &quot;Espace&quot;","block_context":{"text":"Espace","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/espace\/"},"img":{"alt_text":"Mars","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2012\/11\/mars9.jpg?fit=450%2C266&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/06\/mars-water.jpg?fit=1000%2C1000&ssl=1","_links":{"self":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/7294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/comments?post=7294"}],"version-history":[{"count":4,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/7294\/revisions"}],"predecessor-version":[{"id":28610,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/7294\/revisions\/28610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/media\/7295"}],"wp:attachment":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/media?parent=7294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/categories?post=7294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/tags?post=7294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}