{"id":5045,"date":"2009-10-05T14:48:26","date_gmt":"2009-10-05T12:48:26","guid":{"rendered":"http:\/\/www.laterredufutur.com\/accueil1\/?p=5045"},"modified":"2026-06-08T06:23:06","modified_gmt":"2026-06-08T06:23:06","slug":"un-monde-surpeuple","status":"publish","type":"post","link":"https:\/\/www.laterredufutur.com\/accueil\/un-monde-surpeuple\/","title":{"rendered":"Un monde surpeupl\u00e9"},"content":{"rendered":"<div class=\"1665f18d14f35dd9e7566e1a8ac9a3e9\" data-index=\"1\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block; text-align:center;\"\r\n     data-ad-layout=\"in-article\"\r\n     data-ad-format=\"fluid\"\r\n     data-ad-client=\"ca-pub-2860849627502538\"\r\n     data-ad-slot=\"3019501113\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p align=\"justify\"><span style=\"font-size: small;\">2050: 2,3 millliards de bouches de plus \u00e0 nourrir 23-09-2009<br \/>\nLa production alimentaire devra augmenter de 70%; Forum d&rsquo;experts de haut niveau \u00e0 la FAO<br \/>\nseptembre 2009, Rome &#8211; Selon un rapport diffus\u00e9 aujourd&rsquo;hui par la FAO, l&rsquo;agriculture mondiale doit relever des d\u00e9fis de taille: augmenter la production alimentaire de 70% pour nourrir 2,3 milliards de personnes de plus d&rsquo;ici \u00e0 2050, intensifier la lutte contre la pauvret\u00e9 et la faim, utiliser plus efficacement les ressources naturelles qui s&rsquo;amenuisent et s&rsquo;adapter au changement climatique.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">La FAO a convoqu\u00e9 pour le 12 et 13 octobre 2009 un Forum d&rsquo;experts de haut niveau pour discuter des strat\u00e9gies \u00e0 mettre en oeuvre pour relever ces d\u00e9fis.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">Le Forum, intitul\u00e9 \u00ab\u00a0Comment nourrir le monde en 2050\u00a0\u00bb rassemblera quelque 300 experts (universitaires, chercheurs, ONG, secteur priv\u00e9) de pays d\u00e9velopp\u00e9s et en d\u00e9veloppement. Il pr\u00e9parera le terrain \u00e0 la tenue du 16 au 18 novembre 2009 d&rsquo;un nouveau Sommet mondial sur la s\u00e9curit\u00e9 alimentaire.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">Optimisme prudent<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">\u00ab\u00a0La FAO fait preuve d&rsquo;un optimisme prudent en ce qui a trait au potentiel du monde \u00e0 se nourrir d&rsquo;ici \u00e0 2050,\u00a0\u00bb indique M. Hafez Ghanem, Sous-Directeur g\u00e9n\u00e9ral responsable du D\u00e9partement \u00e9conomique et social de la FAO. Toutefois nourrir tout un chacun d&rsquo;ici l\u00e0 n&rsquo;est pas \u00ab\u00a0automatique\u00a0\u00bb \u00e0 moins de relever plusieurs d\u00e9fis de taille&#8230;<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">Selon les projections mondiales, pour am\u00e9liorer l&rsquo;acc\u00e8s \u00e0 la nourriture de gros investissements sont n\u00e9cessaires qui devront s&rsquo;ajouter aux investissements actuels. Sinon, quelque 370 millions de personnes continueraient \u00e0 souffrir de la faim en 2050, soit pr\u00e8s de 5% de la population des pays en d\u00e9veloppement.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">La population mondiale, selon les derni\u00e8res projections des Nations Unies, doit passer de 6,8 milliards \u00e0 9,1 milliards en 2050, soit un tiers de bouches de plus \u00e0 nourrir qu&rsquo;il n&rsquo;y en a aujourd&rsquo;hui.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">Le gros de la croissance d\u00e9mographique se produira dans les pays en d\u00e9veloppement. C&rsquo;est en Afrique subsaharienne, que le taux de croissance sera le plus fort (+108%, soit 910 millions de personnes). En revanche, il sera le plus faible en Asie de l&rsquo;est et du sud-est (+11%, soit 228 millions de personnes).<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">Environ 70% de la population mondiale vivra dans les villes ou les r\u00e9gions urbaines \u00e0 l&rsquo;horizon 2050, soit une augmentation de 49% par rapport \u00e0 aujourd&rsquo;hui.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">Demande en hausse<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">La demande alimentaire va continuer \u00e0 s&rsquo;accro\u00eetre du fait \u00e0 la fois de la croissance d\u00e9mographique et de l&rsquo;augmentation des revenus. La demande de c\u00e9r\u00e9ales (pour l&rsquo;alimentation humaine et animale) doit atteindre quelque 3 milliards de tonnes en 2050.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">La production c\u00e9r\u00e9ali\u00e8re annuelle devra s&rsquo;accro\u00eetre de pr\u00e8s d&rsquo;un milliard de tonnes (elle atteint aujourd&rsquo;hui 2,1 milliard de tonnes).<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">La production de viande devra augmenter de plus de 200 millions de tonnes, totalisant 470 millions de tonnes en 2050, dont 72% seront consomm\u00e9s dans les pays en d\u00e9veloppement (contre 58% aujourd&rsquo;hui).<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">La production de biocarburants pourrait \u00e9galement doper la demande de produits agricoles et ce, en fonction des prix de l&rsquo;\u00e9nergie et des politiques gouvernementales.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">Terres arables<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">Bien que l&rsquo;augmentation de la production alimentaire sera obtenue \u00e0 90% de rendements plus \u00e9lev\u00e9s et de l&rsquo;accroissement de l&rsquo;intensit\u00e9 culturale, les terres arables devront augmenter d&rsquo;environ 120 millions d&rsquo;hectares dans les pays en d\u00e9veloppement, principalement en Afrique subsaharienne et en Am\u00e9rique latine.<\/span><\/p>\n<p>Les terres arables exploit\u00e9es dans les pays d\u00e9velopp\u00e9s diminueront de quelque 50 millions d&rsquo;hectares, bien que cela pourrait \u00eatre modifi\u00e9 par la demande sur les biocarburants.<\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">Globalement, les disponibilit\u00e9s de ressources en terre sont suffisantes pour nourrir la future population mondiale. Toutefois, la FAO avertit que dans leur grande partie les terres disponibles ne conviennent que pour un nombre restreint de cultures, pas n\u00e9cessairement les cultures fortement demand\u00e9es, et ces terres sont concentr\u00e9es dans peu de pays&#8230;<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">Eau<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">Les pr\u00e9l\u00e8vements d&rsquo;eau pour l&rsquo;agriculture irrigu\u00e9e devraient augmenter \u00e0 un rythme plus lent compte tenu du recul de la demande et de la meilleure efficacit\u00e9 d&rsquo;utilisation de l&rsquo;eau, mais ils progresseront n\u00e9anmoins de pr\u00e8s de 11 pour cent d&rsquo;ici \u00e0 2050.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">A l&rsquo;\u00e9chelle mondiale, les ressources d&rsquo;eau douce sont suffisantes, mais r\u00e9parties de fa\u00e7on tr\u00e8s in\u00e9gale, et le manque d&rsquo;eau atteindra des niveaux alarmants dans un nombre croissant de pays ou de r\u00e9gions, en particulier au Proche-Orient\/Afrique du Nord et en Asie du Sud&#8230;.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">Potentiel de rendement<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">Tout bien consid\u00e9r\u00e9, les possibilit\u00e9s d&rsquo;accro\u00eetre les rendements agricoles pour nourrir une population mondiale grandissante semblent consid\u00e9rables, selon la FAO.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">\u00ab\u00a0Si des mesures d&rsquo;incitation socio-\u00e9conomiques appropri\u00e9es ont \u00e9t\u00e9 prises, il reste de gros d\u00e9ficits de rendement \u00e0 combler (diff\u00e9rence entre les rendements r\u00e9alisables d&rsquo;un point de vue agro-\u00e9cologique et les rendements effectifs). Les craintes que les rendements aient atteint un plafond ne semblent pas justifi\u00e9es, sauf dans de rares cas particuliers\u00a0\u00bb.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">R\u00e9gression de la faim dans le monde<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">La FAO pr\u00e9conise des interventions plus vigoureuses pour r\u00e9duire, voire \u00e9liminer le nombre de personnes pauvres et affam\u00e9es dans le monde. Il faut accro\u00eetre les investissements dans l&rsquo;agriculture primaire d&rsquo;environ 60 pour cent et en faire une priorit\u00e9 absolue, car l&rsquo;agriculture ne produit pas seulement de la nourriture mais cr\u00e9e \u00e9galement des revenus et soutient les moyens d&rsquo;existence ruraux.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">La r\u00e9duction de la pauvret\u00e9 requiert en outre des investissements dans les infrastructures rurales (routes, ports, \u00e9nergie, syst\u00e8mes de stockage et d&rsquo;irrigation); des investissements dans les institutions, la recherche et les services de vulgarisation, les titres et droits fonciers, la gestion des risques, les syst\u00e8mes v\u00e9t\u00e9rinaires et de contr\u00f4le de la s\u00e9curit\u00e9 sanitaire des aliments; et des investissements non agricoles, y compris des filets de s\u00e9curit\u00e9 alimentaire et des transferts d&rsquo;esp\u00e8ces aux populations les plus vuln\u00e9rables.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">Faute d&rsquo;investissements et d&rsquo;un d\u00e9veloppement des zones rurales des pays pauvres, la mis\u00e8re et les in\u00e9galit\u00e9s continueront \u00e0 s\u00e9vir dans le monde, m\u00eame si leur ampleur sera consid\u00e9rablement r\u00e9duite par rapport \u00e0 aujourd&rsquo;hui, selon la FAO.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: small;\">extrait et source : <\/span><a href=\"https:\/\/www.fao.org\/\">http:\/\/www.fao.org\/<\/a><\/p>\n<p class=\"bawpvc-ajax-counter\" data-id=\"5045\">(459)<\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>2050: 2,3 millliards de bouches de plus \u00e0 nourrir 23-09-2009 La production alimentaire devra augmenter de 70%; Forum d&rsquo;experts de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":5046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[730,728,3719,2806,3720,731,1324,535,2791,75],"class_list":["post-5045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-monde-futur","tag-hommes","tag-humains","tag-individus","tag-milliards","tag-peuples","tag-population","tag-production","tag-ressources","tag-surpopulation","tag-terre","wpcat-18-id"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p631RN-1jn","jetpack-related-posts":[{"id":3337,"url":"https:\/\/www.laterredufutur.com\/accueil\/vers-un-monde-qui-aura-faim\/","url_meta":{"origin":5045,"position":0},"title":"Vers un monde qui aura faim","author":"Admin","date":"27 f\u00e9vrier 2006","format":false,"excerpt":"Pendant que 20% de la population mondiale utilise les 85% des ressources mondiales, o\u00f9 court notre monde dans ce paradoxe tr\u00e8s humain. Nous avons cr\u00e9\u00e9 les \u00e9l\u00e9ments pour destabiliser notre environnement avec son climat. L\u2019augmentation de la production de nourriture par hectare de terre ne va pas de pair avec\u2026","rel":"","context":"Dans &quot;Monde Futur&quot;","block_context":{"text":"Monde Futur","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/monde-futur\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":15081,"url":"https:\/\/www.laterredufutur.com\/accueil\/si-toutes-vos-bombes-etaient-des-graines-le-monde-mangerait-a-sa-faim-au-lieu-de-courir-a-sa-fin\/","url_meta":{"origin":5045,"position":1},"title":"Si toutes vos bombes \u00e9taient des graines, le monde mangerait \u00e0 sa faim au lieu de courir \u00e0 sa fin !","author":"Admin","date":"6 mai 2017","format":false,"excerpt":"Pendant que des milliards de bombes ont \u00e9t\u00e9 utilis\u00e9es \u00e0 travers le monde et depuis le d\u00e9but du XXeme si\u00e8cle. A ce jour plus d\u20191 milliard de personnes sont sous-aliment\u00e9es, la situation r\u00e9sulte de plusieurs facteurs : production et rendement insuffisant dans plusieurs parties du monde ; in\u00e9gale r\u00e9partition des\u2026","rel":"","context":"Dans &quot;Monde Futur&quot;","block_context":{"text":"Monde Futur","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/monde-futur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2017\/04\/bombes-graines-monde.jpg?fit=960%2C960&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2017\/04\/bombes-graines-monde.jpg?fit=960%2C960&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2017\/04\/bombes-graines-monde.jpg?fit=960%2C960&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2017\/04\/bombes-graines-monde.jpg?fit=960%2C960&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":13394,"url":"https:\/\/www.laterredufutur.com\/accueil\/un-monde-sans-faim\/","url_meta":{"origin":5045,"position":2},"title":"Un monde sans faim","author":"Admin","date":"1 octobre 2016","format":false,"excerpt":"Comment nourrir 9 milliards d'\u00eatres humains en 2050 ? Comment faire pour que 9 milliards d'humains arrivent \u00e0 manger \u00e0 leur faim? Et ce, alors m\u00eame que les contraintes, notamment environnementales, se font de plus en plus pressantes: l'agriculture consomme en effet 70% de l'eau douce de la plan\u00e8te et\u2026","rel":"","context":"Dans &quot;Monde Futur&quot;","block_context":{"text":"Monde Futur","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/monde-futur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2016\/10\/un-monde-sans-faim.jpg?fit=1200%2C531&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2016\/10\/un-monde-sans-faim.jpg?fit=1200%2C531&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2016\/10\/un-monde-sans-faim.jpg?fit=1200%2C531&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2016\/10\/un-monde-sans-faim.jpg?fit=1200%2C531&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2016\/10\/un-monde-sans-faim.jpg?fit=1200%2C531&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":10666,"url":"https:\/\/www.laterredufutur.com\/accueil\/en-2050-il-y-aura-plus-de-plastique-que-de-poisson-dans-locean-salarme-le-forum-de-davos\/","url_meta":{"origin":5045,"position":3},"title":"En 2050, il y aura plus de plastique que de poisson dans l&rsquo;oc\u00e9an s&rsquo;alarme le forum de Davos","author":"Admin","date":"20 janvier 2016","format":false,"excerpt":"Selon un rapport d\u00e9voil\u00e9 ce mardi par le forum de Davos, il y aura plus de plastique que de poisson dans les oc\u00e9ans en 2050... Plus de plastique que de poissons dans les oc\u00e9ans. C\u2019est le sc\u00e9nario catastrophe dress\u00e9 par une \u00e9tude r\u00e9alis\u00e9e avec la fondation de la navigatrice Ellen\u2026","rel":"","context":"Dans &quot;Pollution&quot;","block_context":{"text":"Pollution","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/pollution\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2016\/01\/plastiques-oceans-1.jpg?fit=648%2C415&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2016\/01\/plastiques-oceans-1.jpg?fit=648%2C415&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2016\/01\/plastiques-oceans-1.jpg?fit=648%2C415&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":3202,"url":"https:\/\/www.laterredufutur.com\/accueil\/nous-sommes-tous-responsables\/","url_meta":{"origin":5045,"position":4},"title":"Nous sommes tous responsables","author":"Admin","date":"3 janvier 2006","format":false,"excerpt":"Nous sommes tous responsables, personnellement, de l'avenir de notre Terre. Chacun \u00e0 un r\u00f4le \u00e0 jouer, chacun a le pouvoir et le devoir d'agir et de se mobiliser. Maintenant. Voici un article qui ouvre la nouvelle ann\u00e9e 2006 et d\u00e9montre sans ambiguit\u00e9 que nous devons devenir responsables... Dans le monde,\u2026","rel":"","context":"Dans &quot;Ecologie&quot;","block_context":{"text":"Ecologie","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/ecologie\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2176,"url":"https:\/\/www.laterredufutur.com\/accueil\/vers-un-monde-qui-va-connaitre-la-famine\/","url_meta":{"origin":5045,"position":5},"title":"Vers un monde qui va conna\u00eetre la famine","author":"Admin","date":"16 septembre 2014","format":false,"excerpt":"Pic du phosphore, bient\u00f4t la famine.\u00a0Notre corps contient du phosphore comme les allumettes ! Le pic mondial de production du phosphore devrait avoir lieu au milieu des ann\u00e9es 2030, ce qui veut dire baisse de production alors qu\u2019il faudrait nourrir\u00a0 les 9 milliards d\u2019habitants pr\u00e9vus par les d\u00e9mographes en 2050.\u2026","rel":"","context":"Dans &quot;Monde Futur&quot;","block_context":{"text":"Monde Futur","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/monde-futur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/wordpress\/wp-content\/uploads\/2014\/09\/laterredufutur.com_photos_phosphore.png?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/04\/surpopulation.jpg?fit=377%2C302&ssl=1","_links":{"self":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/5045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/comments?post=5045"}],"version-history":[{"count":2,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/5045\/revisions"}],"predecessor-version":[{"id":5048,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/5045\/revisions\/5048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/media\/5046"}],"wp:attachment":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/media?parent=5045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/categories?post=5045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/tags?post=5045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}