{"id":27977,"date":"2026-04-16T12:00:09","date_gmt":"2026-04-16T10:00:09","guid":{"rendered":"https:\/\/www.laterredufutur.com\/accueil\/?p=27977"},"modified":"2026-04-14T08:48:20","modified_gmt":"2026-04-14T06:48:20","slug":"les-vagues-de-chaleur-oceaniques-amplifient-les-degats-causes-par-les-ouragans","status":"publish","type":"post","link":"https:\/\/www.laterredufutur.com\/accueil\/les-vagues-de-chaleur-oceaniques-amplifient-les-degats-causes-par-les-ouragans\/","title":{"rendered":"Les vagues de chaleur oc\u00e9aniques \u00ab amplifient \u00bb les d\u00e9g\u00e2ts caus\u00e9s par les ouragans"},"content":{"rendered":"<div class=\"1665f18d14f35dd9e7566e1a8ac9a3e9\" data-index=\"1\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block; text-align:center;\"\r\n     data-ad-layout=\"in-article\"\r\n     data-ad-format=\"fluid\"\r\n     data-ad-client=\"ca-pub-2860849627502538\"\r\n     data-ad-slot=\"3019501113\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Une nouvelle \u00e9tude r\u00e9v\u00e8le que les vagues de chaleur marines amplifient consid\u00e9rablement les d\u00e9g\u00e2ts caus\u00e9s par les ouragans et les cyclones tropicaux \u00e0 travers le monde.<\/p>\n<p>Des chercheurs ont examin\u00e9 1 600 cyclones tropicaux \u2013 la cat\u00e9gorie plus large de temp\u00eates qui inclut les ouragans \u2013 qui ont touch\u00e9 terre depuis 1981 et ont constat\u00e9 que ceux qui passaient au-dessus d\u2019eaux extr\u00eamement chaudes \u00e9taient plus susceptibles de s\u2019intensifier rapidement , un probl\u00e8me qui devient de plus en plus fr\u00e9quent.<\/p>\n<p>Cela a entra\u00een\u00e9 une augmentation de 60 % des catastrophes causant des dommages d&rsquo;au moins 1 milliard de dollars \u2013 ajust\u00e9s \u00e0 l&rsquo;inflation \u2013 lorsqu&rsquo;elles ont touch\u00e9 terre, selon une \u00e9tude publi\u00e9e vendredi dans la revue <a href=\"https:\/\/www.science.org\/journal\/sciadv\" target=\"_blank\" rel=\"noopener\">Science Advances<\/a> .<\/p>\n<p>Une meilleure compr\u00e9hension de la mani\u00e8re dont les vagues de chaleur marines amplifient les ouragans pourrait aider les pr\u00e9visionnistes, les responsables des services d&rsquo;urgence et les planificateurs \u00e0 long terme \u00e0 se pr\u00e9parer aux futures temp\u00eates.<\/p>\n<p>L&rsquo;\u00e9tude d\u00e9finit les vagues de chaleur marines comme des \u00e9pisodes de chaleur prolong\u00e9e et touchant de vastes \u00e9tendues d&rsquo;eau, figurant parmi les 10 % des temp\u00e9ratures les plus \u00e9lev\u00e9es jamais enregistr\u00e9es. Elles deviennent de plus en plus dangereuses avec le changement climatique et le r\u00e9chauffement constant des oc\u00e9ans, expliquent les auteurs. L&rsquo;eau chaude alimente les ouragans.<\/p>\n<p>\u00ab Ces vagues de chaleur marines affectent plus de la moiti\u00e9 des cyclones tropicaux qui touchent terre \u00bb, a d\u00e9clar\u00e9 Gregory Foltz, oc\u00e9anographe \u00e0 la National Oceanic and Atmospheric Administration et co-auteur de l&rsquo;\u00e9tude.<\/p>\n<p>\u00ab Ces ph\u00e9nom\u00e8nes se produisent plus pr\u00e8s des c\u00f4tes et plus fr\u00e9quemment, je pense donc que les gens doivent y pr\u00eater attention et savoir qu&rsquo;ils sont plus susceptibles de causer des d\u00e9g\u00e2ts consid\u00e9rables lorsqu&rsquo;ils touchent terre. \u00bb<\/p>\n<p>Il est important pour les m\u00e9t\u00e9orologues qui pr\u00e9voient la trajectoire des temp\u00eates de v\u00e9rifier si ces ouragans traversent une vague de chaleur marine, car ils sont plus susceptibles de s&rsquo;intensifier rapidement, ce qui \u00ab peut potentiellement avoir un impact plus important sur les terres touch\u00e9es \u00bb, a d\u00e9clar\u00e9 Foltz.<\/p>\n<figure id=\"attachment_23932\" aria-describedby=\"caption-attachment-23932\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"23932\" data-permalink=\"https:\/\/www.laterredufutur.com\/accueil\/dossier-de-nouvelles-donnees-montrent-que-le-gulf-stream-continue-de-ralentir-leau-douce-a-cree-un-desequilibre-et-le-rapproche-dun-point-deffondrement\/ouragan-sandy-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/04\/ouragan-sandy.jpg?fit=1200%2C800&amp;ssl=1\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ouragan sandy\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Ouragan Sandy en 2022&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/04\/ouragan-sandy.jpg?fit=800%2C533&amp;ssl=1\" class=\"wp-image-23932 size-large\" src=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/04\/ouragan-sandy.jpg?resize=800%2C533&#038;ssl=1\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/04\/ouragan-sandy.jpg?resize=800%2C533&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/04\/ouragan-sandy.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/04\/ouragan-sandy.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/04\/ouragan-sandy.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-23932\" class=\"wp-caption-text\">Ouragan Sandy en 2022<\/figcaption><\/figure>\n<figure id=\"attachment_19238\" aria-describedby=\"caption-attachment-19238\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19238\" data-permalink=\"https:\/\/www.laterredufutur.com\/accueil\/la-saison-des-ouragans-de-latlantique-commence-apres-trois-ans-de-grosses-tempetes\/image-satellite-prise-le-11-septembre-2018-montrant-louragan-florence-dans-locean-atlantique-suivi-des-ouragans-isaac-et-helene\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2019\/06\/image-satellite-prise-le-11-septembre-2018-montrant-louragan-Florence-dans-loc%C3%A9an-Atlantique-suivi-des-ouragans-Isaac-et-Helene.jpg?fit=1250%2C703&amp;ssl=1\" data-orig-size=\"1250,703\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"image satellite prise le 11 septembre 2018 montrant l&amp;rsquo;ouragan Florence dans l&amp;rsquo;oc\u00e9an Atlantique, suivi des ouragans Isaac et Helene\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Une image satellite prise le 11 septembre 2018 montrant l&amp;rsquo;ouragan Florence dans l&amp;rsquo;oc\u00e9an Atlantique, suivi des ouragans Isaac et Helene. Photo: Getty Images \/ Agence am\u00e9ricaine d&amp;rsquo;observation oc\u00e9anique et atmosph\u00e9rique (NOAA)&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2019\/06\/image-satellite-prise-le-11-septembre-2018-montrant-louragan-Florence-dans-loc%C3%A9an-Atlantique-suivi-des-ouragans-Isaac-et-Helene.jpg?fit=800%2C450&amp;ssl=1\" class=\"wp-image-19238 size-large\" src=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2019\/06\/image-satellite-prise-le-11-septembre-2018-montrant-louragan-Florence-dans-loc%C3%A9an-Atlantique-suivi-des-ouragans-Isaac-et-Helene.jpg?resize=800%2C450&#038;ssl=1\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2019\/06\/image-satellite-prise-le-11-septembre-2018-montrant-louragan-Florence-dans-loc%C3%A9an-Atlantique-suivi-des-ouragans-Isaac-et-Helene.jpg?resize=800%2C450&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2019\/06\/image-satellite-prise-le-11-septembre-2018-montrant-louragan-Florence-dans-loc%C3%A9an-Atlantique-suivi-des-ouragans-Isaac-et-Helene.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2019\/06\/image-satellite-prise-le-11-septembre-2018-montrant-louragan-Florence-dans-loc%C3%A9an-Atlantique-suivi-des-ouragans-Isaac-et-Helene.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2019\/06\/image-satellite-prise-le-11-septembre-2018-montrant-louragan-Florence-dans-loc%C3%A9an-Atlantique-suivi-des-ouragans-Isaac-et-Helene.jpg?resize=580%2C326&amp;ssl=1 580w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2019\/06\/image-satellite-prise-le-11-septembre-2018-montrant-louragan-Florence-dans-loc%C3%A9an-Atlantique-suivi-des-ouragans-Isaac-et-Helene.jpg?resize=174%2C98&amp;ssl=1 174w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2019\/06\/image-satellite-prise-le-11-septembre-2018-montrant-louragan-Florence-dans-loc%C3%A9an-Atlantique-suivi-des-ouragans-Isaac-et-Helene.jpg?w=1250&amp;ssl=1 1250w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-19238\" class=\"wp-caption-text\">Une image satellite prise le 11 septembre 2018 montrant l&rsquo;ouragan Florence dans l&rsquo;oc\u00e9an Atlantique, suivi des ouragans Isaac et Helene. Photo: Getty Images \/ Agence am\u00e9ricaine d&rsquo;observation oc\u00e9anique et atmosph\u00e9rique (NOAA)<\/figcaption><\/figure>\n<p>\u00ab Il suffit de regarder les ouragans d\u00e9vastateurs qui ont frapp\u00e9 les \u00c9tats-Unis en 2023 \u00bb, a d\u00e9clar\u00e9 Hamed Moftakhari, co-auteur de l&rsquo;\u00e9tude et professeur de g\u00e9nie c\u00f4tier \u00e0 l&rsquo;Universit\u00e9 d&rsquo;Alabama, qui \u00e9tudie les risques compos\u00e9s.<\/p>\n<p>\u00ab L\u2019histoire d\u2019 Helene et de Milton montre que si l\u2019oc\u00e9an se r\u00e9chauffe, il fournit le carburant n\u00e9cessaire pour amplifier consid\u00e9rablement les cyclones tropicaux, m\u00eame en cascade. Ainsi, en quelques semaines, deux ouragans s\u2019intensifiant rapidement pourraient toucher terre sur la c\u00f4te ouest de la Floride \u00bb, a d\u00e9clar\u00e9 Moftakhari.<\/p>\n<p>\u00ab C\u2019est choquant, mais cela devrait aussi inqui\u00e9ter la population. \u00bb<\/p>\n<p>L&rsquo;\u00e9tude mentionne \u00e9galement l&rsquo;ouragan Otis d&rsquo;octobre 2023, qui s&rsquo;est rapidement intensifi\u00e9, passant d&rsquo;une temp\u00eate tropicale \u00e0 un ouragan de cat\u00e9gorie 5 en une seule journ\u00e9e, puis a caus\u00e9 environ 16 milliards de dollars de d\u00e9g\u00e2ts et 52 d\u00e9c\u00e8s lorsqu&rsquo;il a touch\u00e9 terre pr\u00e8s d&rsquo;Acapulco, au Mexique, avec des vents de 265 km\/h.<\/p>\n<figure id=\"attachment_27980\" aria-describedby=\"caption-attachment-27980\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"27980\" data-permalink=\"https:\/\/www.laterredufutur.com\/accueil\/les-vagues-de-chaleur-oceaniques-amplifient-les-degats-causes-par-les-ouragans\/ouragan-otis-2023\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/ouragan-otis-2023.png?fit=856%2C632&amp;ssl=1\" data-orig-size=\"856,632\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ouragan otis 2023\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Ouragan Otis en 2023&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/ouragan-otis-2023.png?fit=800%2C591&amp;ssl=1\" class=\"wp-image-27980 size-large\" src=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/ouragan-otis-2023.png?resize=800%2C591&#038;ssl=1\" alt=\"\" width=\"800\" height=\"591\" srcset=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/ouragan-otis-2023.png?resize=800%2C591&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/ouragan-otis-2023.png?resize=300%2C221&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/ouragan-otis-2023.png?resize=80%2C60&amp;ssl=1 80w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/ouragan-otis-2023.png?resize=768%2C567&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/ouragan-otis-2023.png?resize=480%2C354&amp;ssl=1 480w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/ouragan-otis-2023.png?w=856&amp;ssl=1 856w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-27980\" class=\"wp-caption-text\">Ouragan Otis en 2023<\/figcaption><\/figure>\n<p>Les chercheurs ont indiqu\u00e9 que les d\u00e9g\u00e2ts plus importants, compar\u00e9s \u00e0 ceux caus\u00e9s par les temp\u00eates qui n&rsquo;ont pas travers\u00e9 de vagues de chaleur marines, n&rsquo;\u00e9taient pas dus \u00e0 un d\u00e9veloppement c\u00f4tier accru.<\/p>\n<p>Les temp\u00eates qui ont travers\u00e9 des eaux chaudes et frapp\u00e9 des c\u00f4tes urbanis\u00e9es ont \u00e9t\u00e9 compar\u00e9es \u00e0 d&rsquo;autres temp\u00eates qui ont frapp\u00e9 des zones urbanis\u00e9es similaires mais sans traverser d&rsquo;eaux chaudes, a d\u00e9clar\u00e9 Soheil Radfar, auteur principal de l&rsquo;\u00e9tude et scientifique sp\u00e9cialis\u00e9 dans la mod\u00e9lisation des risques d&rsquo;ouragans \u00e0 l&rsquo;universit\u00e9 de Princeton.<\/p>\n<p>La science sait depuis longtemps que l&rsquo;eau chaude alimente et renforce souvent les cyclones tropicaux, \u00e9tablissant ainsi un lien de causalit\u00e9 plus \u00e9vident.<\/p>\n<p>Cela signifie que l&rsquo;avenir s&rsquo;annonce plus dangereux, a d\u00e9clar\u00e9 Radfar.<\/p>\n<p>\u00ab Tous ces \u00e9l\u00e9ments du puzzle vont repr\u00e9senter un v\u00e9ritable d\u00e9fi pour l\u2019environnement c\u00f4tier au cours des quatre prochaines d\u00e9cennies, avec une intensification plus rapide et des vagues de chaleur marines plus fr\u00e9quentes \u00bb, a d\u00e9clar\u00e9 Radfar.<\/p>\n<figure id=\"attachment_27982\" aria-describedby=\"caption-attachment-27982\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"27982\" data-permalink=\"https:\/\/www.laterredufutur.com\/accueil\/les-vagues-de-chaleur-oceaniques-amplifient-les-degats-causes-par-les-ouragans\/illustration-degats-ouragan-otis-en-2023\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/illustration-degats-ouragan-otis-en-2023.jpg?fit=1024%2C1024&amp;ssl=1\" data-orig-size=\"1024,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"illustration degats ouragan otis en 2023\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;illustration degats ouragan otis en 2023&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/illustration-degats-ouragan-otis-en-2023.jpg?fit=800%2C800&amp;ssl=1\" class=\"wp-image-27982 size-large\" src=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/illustration-degats-ouragan-otis-en-2023.jpg?resize=800%2C800&#038;ssl=1\" alt=\"\" width=\"800\" height=\"800\" srcset=\"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/illustration-degats-ouragan-otis-en-2023.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/illustration-degats-ouragan-otis-en-2023.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/illustration-degats-ouragan-otis-en-2023.jpg?resize=60%2C60&amp;ssl=1 60w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/illustration-degats-ouragan-otis-en-2023.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/illustration-degats-ouragan-otis-en-2023.jpg?resize=144%2C144&amp;ssl=1 144w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/illustration-degats-ouragan-otis-en-2023.jpg?resize=928%2C928&amp;ssl=1 928w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/illustration-degats-ouragan-otis-en-2023.jpg?resize=480%2C480&amp;ssl=1 480w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/illustration-degats-ouragan-otis-en-2023.jpg?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/illustration-degats-ouragan-otis-en-2023.jpg?w=1024&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-27982\" class=\"wp-caption-text\">illustration degats ouragan otis en 2023<\/figcaption><\/figure>\n<p>Cela \u00ab va s&rsquo;av\u00e9rer extr\u00eamement co\u00fbteux et effrayant pour l&rsquo;environnement c\u00f4tier, et cela va provoquer d&rsquo;autres catastrophes se chiffrant en milliards de dollars \u00e0 l&rsquo;avenir. \u00bb<\/p>\n<p>Moftakhari a d\u00e9clar\u00e9 : \u00ab Du point de vue de l&rsquo;ing\u00e9nierie c\u00f4ti\u00e8re et de la gestion des risques, cela a des implications importantes sur la mani\u00e8re dont les gouvernements planifient, con\u00e7oivent et r\u00e9agissent \u00e0 ces dangers. \u00bb<\/p>\n<p>D&rsquo;apr\u00e8s Moftakhari, les plans d&rsquo;\u00e9vacuation doivent tenir compte du fait que les temp\u00eates traversant des zones oc\u00e9aniques chaudes sont plus susceptibles de s&rsquo;intensifier rapidement et de repr\u00e9senter une menace accrue. Des alertes et des m\u00e9canismes de d\u00e9clenchement pr\u00e9coces pour l&rsquo;\u00e9vacuation des populations pourraient s&rsquo;av\u00e9rer n\u00e9cessaires en cas de vagues de chaleur marines.<\/p>\n<p>\u00ab Les plans de protection contre les inondations, les syst\u00e8mes de drainage et les digues doivent tous \u00eatre mis \u00e0 jour pour tenir compte de l&rsquo;aggravation des temp\u00eates \u00bb, a-t-il d\u00e9clar\u00e9.<\/p>\n<p>Des scientifiques externes ont d\u00e9clar\u00e9 que l&rsquo;\u00e9tude concorde avec les connaissances actuelles sur la physique des ouragans et du changement climatique, tout en fournissant une estimation plus pr\u00e9cise de la probabilit\u00e9 de d\u00e9g\u00e2ts consid\u00e9rables en pr\u00e9sence de vagues de chaleur marines.<\/p>\n<p>\u00ab Le changement climatique provoque des vagues de chaleur marines plus intenses et plus longues. Les cyclones tropicaux puisent leur \u00e9nergie et g\u00e9n\u00e8rent de fortes pluies gr\u00e2ce \u00e0 l&rsquo;\u00e9vaporation des eaux chaudes de l&rsquo;oc\u00e9an \u00bb, a d\u00e9clar\u00e9 Brian Tang, professeur de sciences atmosph\u00e9riques \u00e0 l&rsquo;Universit\u00e9 d&rsquo;Albany, qui n&rsquo;a pas particip\u00e9 \u00e0 l&rsquo;\u00e9tude.<\/p>\n<p>\u00ab Il est plausible que les vagues de chaleur marines amplifient la puissance des ouragans, \u00e0 condition que d&rsquo;autres conditions environnementales soient favorables \u00e0 leur intensification. En r\u00e9alit\u00e9, les d\u00e9s sont pip\u00e9s. \u00bb<\/p>\n<p>Adaptation <a href=\"https:\/\/www.laterredufutur.com\/accueil\/\" target=\"_blank\" rel=\"noopener\">Terra Projects<\/a><\/p>\n<p>Source : <a href=\"https:\/\/www.sciencealert.com\/ocean-heat-waves-are-supercharging-hurricane-damage-scientists-warn\" target=\"_blank\" rel=\"noopener\">https:\/\/www.sciencealert.com\/<\/a><\/p>\n<p class=\"bawpvc-ajax-counter\" data-id=\"27977\">(57)<\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Une nouvelle \u00e9tude r\u00e9v\u00e8le que les vagues de chaleur marines amplifient consid\u00e9rablement les d\u00e9g\u00e2ts caus\u00e9s par les ouragans et les&#8230;<\/p>\n","protected":false},"author":1,"featured_media":27982,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[20,21],"tags":[316,7662,1721,241,232,152,3043],"class_list":["post-27977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-climat","category-evenement-brutal","tag-chaleur","tag-dome-de-chaleur","tag-eau-chaude","tag-ocean","tag-ouragans","tag-sst","tag-typhons","wpcat-20-id","wpcat-21-id"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p631RN-7hf","jetpack-related-posts":[{"id":3016,"url":"https:\/\/www.laterredufutur.com\/accueil\/au-sein-dun-ouragan\/","url_meta":{"origin":27977,"position":0},"title":"Au sein d&rsquo;un Ouragan","author":"Admin","date":"28 ao\u00fbt 2005","format":false,"excerpt":"Selon certains experts, Katrina pourrait \u00eatre l'ouragan le plus puissant mena\u00e7ant les Etats-Unis depuis l'ouragan Camille en 1969, et faire de nombreuses victimes. Camille avait fait 256 morts en traversant notamment le Mississippi et la Louisiane. Mais actuellement Il s'agit d'un OURAGAN MAJEUR dont les cons\u00e9quences seront catastrophiques pour les\u2026","rel":"","context":"Dans &quot;Ev\u00e8nement Brutal&quot;","block_context":{"text":"Ev\u00e8nement Brutal","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/evenement-brutal\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2005\/08\/ouragan-Katrina-2005.png?fit=1200%2C1109&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2005\/08\/ouragan-Katrina-2005.png?fit=1200%2C1109&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2005\/08\/ouragan-Katrina-2005.png?fit=1200%2C1109&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2005\/08\/ouragan-Katrina-2005.png?fit=1200%2C1109&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2005\/08\/ouragan-Katrina-2005.png?fit=1200%2C1109&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2576,"url":"https:\/\/www.laterredufutur.com\/accueil\/les-ouragans-se-rapprochent-de-leurope\/","url_meta":{"origin":27977,"position":1},"title":"Les ouragans se rapprochent-ils vraiment de l&rsquo;Europe ?","author":"Admin","date":"14 d\u00e9cembre 2004","format":false,"excerpt":"Pendant longtemps, les Europ\u00e9ens ont observ\u00e9 les ouragans comme des ph\u00e9nom\u00e8nes lointains, r\u00e9serv\u00e9s aux Cara\u00efbes, au golfe du Mexique ou \u00e0 la c\u00f4te est des \u00c9tats-Unis. Pourtant, depuis plusieurs ann\u00e9es, les m\u00e9t\u00e9orologues surveillent avec une attention croissante l'\u00e9volution de ces syst\u00e8mes tropicaux dans l'Atlantique. La raison est simple : l'oc\u00e9an\u2026","rel":"","context":"Dans &quot;Ev\u00e8nement Brutal&quot;","block_context":{"text":"Ev\u00e8nement Brutal","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/evenement-brutal\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2004\/12\/Ouragans-europe.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2004\/12\/Ouragans-europe.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2004\/12\/Ouragans-europe.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2004\/12\/Ouragans-europe.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2004\/12\/Ouragans-europe.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":26270,"url":"https:\/\/www.laterredufutur.com\/accueil\/comment-une-intensification-rapide-a-donne-naissance-a-deux-ouragans-monstres-en-une-semaine\/","url_meta":{"origin":27977,"position":2},"title":"Comment une intensification rapide a donn\u00e9 naissance \u00e0 deux ouragans monstres en une semaine","author":"Admin","date":"27 septembre 2024","format":false,"excerpt":"Les eaux chaudes ont renforc\u00e9 l'ouragan H\u00e9l\u00e8ne dans le golfe du Mexique et l'ouragan John dans le Pacifique oriental. L'un des ouragans les plus \u00e9tendus jamais enregistr\u00e9s a frapp\u00e9 la c\u00f4te du golfe de Floride le 26 septembre sous la forme d'une puissante temp\u00eate de cat\u00e9gorie 4, inondant la c\u00f4te\u2026","rel":"","context":"Dans &quot;Ev\u00e8nement Brutal&quot;","block_context":{"text":"Ev\u00e8nement Brutal","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/evenement-brutal\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2024\/09\/ouragan-Helene1.jpg?fit=1200%2C651&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2024\/09\/ouragan-Helene1.jpg?fit=1200%2C651&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2024\/09\/ouragan-Helene1.jpg?fit=1200%2C651&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2024\/09\/ouragan-Helene1.jpg?fit=1200%2C651&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2024\/09\/ouragan-Helene1.jpg?fit=1200%2C651&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3274,"url":"https:\/\/www.laterredufutur.com\/accueil\/les-cyclones-sement-la-tempete-chez-les-scientifiques\/","url_meta":{"origin":27977,"position":3},"title":"Les cyclones s\u00e8ment la temp\u00eate chez les scientifiques","author":"Admin","date":"20 janvier 2006","format":false,"excerpt":"Voici un article qui met le trouble chez les scientifiques et dont les mod\u00e8les statistiques sont remis s\u00e9rieusement remis en cause. Bien des donn\u00e9es \u00e9taient dans le flou concernant les ouragans. L'ann\u00e9e cyclonique 2005 apporte la preuve que les mod\u00e8les peuvent \u00eatre erron\u00e9s. Certains jettent l'\u00e9ponge face \u00e0 des \u00e9v\u00e8nements\u2026","rel":"","context":"Dans &quot;Climat&quot;","block_context":{"text":"Climat","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/climat\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/04\/scientifique.jpeg?fit=270%2C400&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13144,"url":"https:\/\/www.laterredufutur.com\/accueil\/situation-incroyable-dans-le-pacifique-lile-dhawai-pour-la-premiere-fois-dans-lhistoire-recente-menacee-par-deux-ouragans\/","url_meta":{"origin":27977,"position":4},"title":"Situation incroyable dans le Pacifique, l&rsquo;\u00eele d&rsquo;Hawa\u00ef pour la premi\u00e8re fois dans l&rsquo;histoire r\u00e9cente menac\u00e9e par deux ouragans","author":"Admin","date":"30 ao\u00fbt 2016","format":false,"excerpt":"Pour la premi\u00e8re fois dans l'histoire de l'\u00eele d'Hawaii, il est menac\u00e9 par le passage de deux ouragans cons\u00e9cutifs. Avoir des heures tr\u00e8s pr\u00e9ocupantes pour l'\u00eele d'Hawaii, le plus grand c\u00e9l\u00e8bre archipel du Pacifique, est sous la loupe de deux ouragans distincts alors qu'ils se pr\u00e9parent \u00e0 le toucher, en\u2026","rel":"","context":"Dans &quot;Ev\u00e8nement Brutal&quot;","block_context":{"text":"Ev\u00e8nement Brutal","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/evenement-brutal\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2016\/08\/ouragans-pacifique-hawai-30aout-2016-2.jpg?fit=711%2C397&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2016\/08\/ouragans-pacifique-hawai-30aout-2016-2.jpg?fit=711%2C397&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2016\/08\/ouragans-pacifique-hawai-30aout-2016-2.jpg?fit=711%2C397&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2016\/08\/ouragans-pacifique-hawai-30aout-2016-2.jpg?fit=711%2C397&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4588,"url":"https:\/\/www.laterredufutur.com\/accueil\/les-ouragans\/","url_meta":{"origin":27977,"position":5},"title":"Les Ouragans","author":"Admin","date":"7 septembre 2008","format":false,"excerpt":"LES OURAGANS... (Ici Katrina septembre 2005) ... Les \"vents\" de la mer QU'EST-CE QU'UN OURAGAN ? C'est un cyclone d'origine tropicale, d'une violence extraordinaire. Mais ce n'est pas le plus gros cyclone; certaines temp\u00eates extra-tropicales sont plus \u00e9tendues. Ce n'est pas le plus furieux; les tornades sont plus intenses. Cependant,\u2026","rel":"","context":"Dans &quot;Ev\u00e8nement Brutal&quot;","block_context":{"text":"Ev\u00e8nement Brutal","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/evenement-brutal\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/04\/katrina-2005.jpg?fit=317%2C293&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2026\/04\/illustration-degats-ouragan-otis-en-2023.jpg?fit=1024%2C1024&ssl=1","_links":{"self":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/27977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/comments?post=27977"}],"version-history":[{"count":4,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/27977\/revisions"}],"predecessor-version":[{"id":27983,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/27977\/revisions\/27983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/media\/27982"}],"wp:attachment":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/media?parent=27977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/categories?post=27977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/tags?post=27977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}