{"id":24517,"date":"2022-10-30T20:14:01","date_gmt":"2022-10-30T18:14:01","guid":{"rendered":"https:\/\/www.laterredufutur.com\/accueil\/?p=24517"},"modified":"2022-10-30T20:14:01","modified_gmt":"2022-10-30T18:14:01","slug":"un-volcan-en-cause-dans-les-fortes-chaleurs-de-notre-planete-cette-annee","status":"publish","type":"post","link":"https:\/\/www.laterredufutur.com\/accueil\/un-volcan-en-cause-dans-les-fortes-chaleurs-de-notre-planete-cette-annee\/","title":{"rendered":"Un volcan en cause dans les fortes chaleurs de notre plan\u00e8te cette ann\u00e9e ?"},"content":{"rendered":"<div class=\"1665f18d14f35dd9e7566e1a8ac9a3e9\" data-index=\"1\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block; text-align:center;\"\r\n     data-ad-layout=\"in-article\"\r\n     data-ad-format=\"fluid\"\r\n     data-ad-client=\"ca-pub-2860849627502538\"\r\n     data-ad-slot=\"3019501113\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Entr\u00e9 en \u00e9ruption en janvier, le volcan Hunga Tonga est-il responsable des fortes chaleurs de l&rsquo;ann\u00e9e 2022? Les r\u00e9sultats d&rsquo;une \u00e9tude le laissent \u00e0 penser.<\/p>\n<p>Apr\u00e8s un \u00e9t\u00e9 record, les temp\u00e9ratures de cet automne atteignent des niveaux jamais vus. Et la France n&rsquo;est pas la seule touch\u00e9e. Partout sur le globe, des anomalies brutales ont \u00e9t\u00e9 enregistr\u00e9es cette ann\u00e9e. Des zones enti\u00e8res ont \u00e9t\u00e9 frapp\u00e9es de temp\u00e9ratures d\u00e9passant les 50\u00b0C quand les valeurs des normales de saison ne sont pas, partout ailleurs, r\u00e9guli\u00e8rement explos\u00e9es.<\/p>\n<p>Si le r\u00e9chauffement climatique est bien entendu le premier responsable, un autre facteur peut expliquer ces changements tr\u00e8s rapides, in\u00e9dits.<\/p>\n<p>Publi\u00e9s d\u00e9but juillet, les r\u00e9sultats d&rsquo;une \u00e9tude publi\u00e9e dans Advancing Earth and Space Science (AGU) semblent \u00e9clairer d&rsquo;un nouveau jour les changements climatiques brutaux de cette ann\u00e9e.<\/p>\n<p>En effet, selon l&rsquo;interpr\u00e9tation des r\u00e9sultats de cette \u00e9tude, l&rsquo;\u00e9ruption du volcan Hunga Tonga, en janvier 2022 dans le Pacifique, pourrait avoir contribu\u00e9 \u00e0 la chaleur effr\u00e9n\u00e9e et persistante de cette ann\u00e9e.<\/p>\n<p>Les grosses \u00e9ruptions modifient le climat<br \/>\nC&rsquo;est le service m\u00e9t\u00e9o de Catalogne qui s&rsquo;appuie sur cette \u00e9tude pour rappeler que les \u00e9ruptions volcaniques violentes ont toujours eu des cons\u00e9quences sur le temps et le climat de la plan\u00e8te.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"ca\" dir=\"ltr\">Quan les erupcions volc\u00e0niques prop de l&#39;equador injecten molts gasos i aerosols a l&#39;estratosfera fan augmentar la radiaci\u00f3 solar reflectida pel Planeta i baixa la temperatura a la superf\u00edcie. S&#39;estima que el 1991 l&#39;erupci\u00f3 del <a href=\"https:\/\/twitter.com\/hashtag\/Pinatubo?src=hash&amp;ref_src=twsrc%5Etfw\">#Pinatubo<\/a> provoc\u00e0 un refredament global de 0,5\u202f\u00b0C.<\/p>\n<p>&mdash; Meteocat (@meteocat) <a href=\"https:\/\/twitter.com\/meteocat\/status\/1584922979233943552?ref_src=twsrc%5Etfw\">October 25, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Et de rappeler ce refroidissement de la plan\u00e8te survenu apr\u00e8s l&rsquo;\u00e9ruption du Pinatubo en 1991 et, surtout celui qui avait suivi celle du volcan Tambora en 1815, qui a \u00e9t\u00e9 d&rsquo;une telle ampleur que les cendres et les gaz ont modifi\u00e9 le bilan \u00e9nerg\u00e9tique de la plan\u00e8te, avec une ann\u00e9e 1816 connue comme celle\u2026 sans \u00e9t\u00e9.<\/p>\n<p>L&rsquo;\u00e9ruption du Hunga Tonga a-t-elle pu pour provoquer la r\u00e9action inverse cette ann\u00e9e?<\/p>\n<p>Des rejets d&rsquo;eau de 55 kilom\u00e8tres de hauteur<br \/>\nCette \u00e9ruption survenue en janvier dernier a d\u00e9gag\u00e9 une grande quantit\u00e9 de gaz dans l&rsquo;atmosph\u00e8re qui a boulevers\u00e9 le bilan \u00e9nerg\u00e9tique de la plan\u00e8te avec une r\u00e9duction de l&rsquo;intensit\u00e9 du soleil qui a impliqu\u00e9 le refroidissement de l&rsquo;atmosph\u00e8re. De plus, l&rsquo;apport colossal d&rsquo;eau inject\u00e9e dans l&rsquo;atmosph\u00e8re, jusqu&rsquo;\u00e0 55 km de hauteur, est sans pr\u00e9c\u00e9dent et a \u00e9t\u00e9 si \u00e9lev\u00e9 qu&rsquo;il pourrait mettre des ann\u00e9es \u00e0 se dissiper, selon les r\u00e9sultats de cette \u00e9tude.<\/p>\n<p>Quelles sont les cons\u00e9quences de ces 150 millions de tonnes de vapeur d&rsquo;eau rejet\u00e9es dans la stratosph\u00e8re? Selon les donn\u00e9es de la Nasa, cela a entra\u00een\u00e9 un exc\u00e8s d&rsquo;eau de 10% par rapport \u00e0 la quantit\u00e9 normale dans la stratosph\u00e8re. La vapeur d&rsquo;eau est l&rsquo;un des principaux gaz \u00e0 effet de serre, avec une contribution qui oscille entre 36 %, avec un ciel d\u00e9gag\u00e9, et 85 %, avec des nuages, \u00e9voque M\u00e9t\u00e9oCat.<\/p>\n<p>Conjugu\u00e9e au r\u00e9chauffement climatique, l&rsquo;\u00e9ruption du volcan Hunga Tonga pourrait donc avoir modifi\u00e9 de quelques dixi\u00e8mes de degr\u00e9 la chaleur globale et, au final, contribu\u00e9 de mani\u00e8re exceptionnelle \u00e0 ces temp\u00e9ratures anormalement \u00e9lev\u00e9es d&rsquo;une ann\u00e9e 2022 hors norme.<\/p>\n<p>source : <a href=\"https:\/\/www.lindependant.fr\/2022\/10\/28\/meteo-une-eruption-volcanique-responsable-des-chaleurs-exceptionnellement-elevees-de-cette-annee-2022-10767105.php\" rel=\"noopener\" target=\"_blank\">https:\/\/www.lindependant.fr\/<\/a><\/p>\n<p class=\"bawpvc-ajax-counter\" data-id=\"24517\">(1059)<\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Entr\u00e9 en \u00e9ruption en janvier, le volcan Hunga Tonga est-il responsable des fortes chaleurs de l&rsquo;ann\u00e9e 2022? Les r\u00e9sultats d&rsquo;une&#8230;<\/p>\n","protected":false},"author":1,"featured_media":23642,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Un volcan en cause dans les fortes chaleurs de notre plan\u00e8te cette ann\u00e9e ? @laterredufutur.com Terra Projects","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[20,19],"tags":[93,7831,5755,557,48],"class_list":["post-24517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-climat","category-seismes-et-volcans","tag-co2","tag-hunga-tonga-hunga-haapai","tag-tonga","tag-vapeur-deau","tag-volcan","wpcat-20-id","wpcat-19-id"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p631RN-6nr","jetpack-related-posts":[{"id":26224,"url":"https:\/\/www.laterredufutur.com\/accueil\/leruption-du-tonga-qui-a-deverse-150-tonnes-de-vapeur-deau-dans-la-stratosphere-a-affecte-latmosphere-pour-de-nombreuses-annees\/","url_meta":{"origin":24517,"position":0},"title":"L&rsquo;\u00e9ruption du Tonga, qui a d\u00e9vers\u00e9 150 tonnes de vapeur d&rsquo;eau dans la stratosph\u00e8re, a affect\u00e9 l&rsquo;atmosph\u00e8re pour de nombreuses ann\u00e9es ?","author":"Admin","date":"12 septembre 2024","format":false,"excerpt":"Une nouvelle \u00e9tude s'appuie sur des recherches ant\u00e9rieures concernant les effets du volcan sous-marin sur le climat. Le 15 janvier 2022, le volcan sous-marin Hunga Tonga-Hunga Ha'apai est entr\u00e9 en \u00e9ruption, d\u00e9clenchant un puissant tsunami qui a d\u00e9truit des maisons et caus\u00e9 la mort de quatre personnes dans l'ensemble des\u2026","rel":"","context":"Dans &quot;Seismes\/Volcans&quot;","block_context":{"text":"Seismes\/Volcans","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/seismes-et-volcans\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/explosion-volcanique-tonga.jpg?fit=1040%2C1120&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/explosion-volcanique-tonga.jpg?fit=1040%2C1120&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/explosion-volcanique-tonga.jpg?fit=1040%2C1120&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/explosion-volcanique-tonga.jpg?fit=1040%2C1120&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":26017,"url":"https:\/\/www.laterredufutur.com\/accueil\/la-violente-eruption-du-tonga-a-provoque-une-forte-augmentation-des-temperatures-mondiales\/","url_meta":{"origin":24517,"position":1},"title":"La violente \u00e9ruption du Tonga a provoqu\u00e9 une forte augmentation des temp\u00e9ratures mondiales","author":"Admin","date":"26 juin 2024","format":false,"excerpt":"La violente \u00e9ruption sous-marine du Tonga en janvier 2022 a inject\u00e9 une \u00e9norme quantit\u00e9 de vapeur d'eau de pr\u00e8s de 150 m\u00e9gatonnes dans l'atmosph\u00e8re, ce qui, proportionnellement, a augment\u00e9 la quantit\u00e9 d'eau dans l'atmosph\u00e8re d'environ 14 %. Les climatologues ont d'abord \u00e9t\u00e9 choqu\u00e9s par l'ampleur et la f\u00e9rocit\u00e9 de l'\u00e9ruption\u2026","rel":"","context":"Dans &quot;Climat&quot;","block_context":{"text":"Climat","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/climat\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/explosion-volcanique-tonga.jpg?fit=1040%2C1120&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/explosion-volcanique-tonga.jpg?fit=1040%2C1120&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/explosion-volcanique-tonga.jpg?fit=1040%2C1120&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/explosion-volcanique-tonga.jpg?fit=1040%2C1120&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":26330,"url":"https:\/\/www.laterredufutur.com\/accueil\/leruption-du-tonga-hunga-a-ete-la-plus-puissante-depuis-celle-du-krakatoa-en-1883\/","url_meta":{"origin":24517,"position":2},"title":"L&rsquo;\u00e9ruption du Tonga-Hunga a \u00e9t\u00e9 la plus puissante depuis celle du Krakatoa en 1883","author":"Admin","date":"22 octobre 2024","format":false,"excerpt":"Le 15 janvier 2022, notre plan\u00e8te a connu une \u00e9ruption majeure avec l'explosion colossale du volcan Tonga\u2013Hunga dans l'oc\u00e9an Pacifique sud. Il s'agit sans doute de la plus forte \u00e9ruption volcanique depuis celle du volcan indon\u00e9sien Krakatoa en 1883 Hunga Tonga-Hunga Ha'apai est un volcan sous-marin de l'Archipel de Tonga\u2026","rel":"","context":"Dans &quot;Seismes\/Volcans&quot;","block_context":{"text":"Seismes\/Volcans","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/seismes-et-volcans\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2024\/10\/explosion-volcan.jpg?fit=1024%2C1024&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2024\/10\/explosion-volcan.jpg?fit=1024%2C1024&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2024\/10\/explosion-volcan.jpg?fit=1024%2C1024&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2024\/10\/explosion-volcan.jpg?fit=1024%2C1024&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":23637,"url":"https:\/\/www.laterredufutur.com\/accueil\/hunga-tonga-hunga-haapai-est-entre-en-eruption-aux-iles-tonga\/","url_meta":{"origin":24517,"position":3},"title":"Hunga-Tonga-Hunga-Ha&rsquo;apai est entr\u00e9 en \u00e9ruption aux iles Tonga","author":"Admin","date":"14 janvier 2022","format":false,"excerpt":"Hunga-Tonga-Hunga-Ha'apai, qui s'est form\u00e9 apr\u00e8s une \u00e9ruption sous-marine en d\u00e9cembre 2014, est entr\u00e9 en \u00e9ruption vendredi 14 janvier 2021, envoyant des cendres, de la vapeur et du gaz \u00e0 pr\u00e8s de 20 kilom\u00e8tres dans l'atmosph\u00e8re. Il y aurait aussi un risque de pluies acides. https:\/\/twitter.com\/i\/status\/1481759313588854784 Le volcan \u00e9tait entr\u00e9 en\u2026","rel":"","context":"Dans &quot;Seismes\/Volcans&quot;","block_context":{"text":"Seismes\/Volcans","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/seismes-et-volcans\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/Hunga-Tonga-Hunga-Haapai-volcan-1.jpg?fit=990%2C660&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/Hunga-Tonga-Hunga-Haapai-volcan-1.jpg?fit=990%2C660&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/Hunga-Tonga-Hunga-Haapai-volcan-1.jpg?fit=990%2C660&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/Hunga-Tonga-Hunga-Haapai-volcan-1.jpg?fit=990%2C660&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":24051,"url":"https:\/\/www.laterredufutur.com\/accueil\/leruption-volcanique-geante-des-tonga-etait-aussi-puissante-que-celle-du-krakatoa-en-1883-revelent-des-scientifiques\/","url_meta":{"origin":24517,"position":4},"title":"L&rsquo;\u00e9ruption volcanique g\u00e9ante des Tonga \u00e9tait aussi puissante que celle du Krakatoa en 1883, r\u00e9v\u00e8lent des scientifiques","author":"Admin","date":"17 mai 2022","format":false,"excerpt":"Un volcan sous-marin est entr\u00e9 en \u00e9ruption en janvier 2022 pr\u00e8s de la nation des Tonga, dans le Pacifique, et a envoy\u00e9 d'\u00e9normes ondes de pression dans l'atmosph\u00e8re terrestre, o\u00f9 elles ont balay\u00e9 la plan\u00e8te \u00e0 plusieurs reprises. Selon une nouvelle \u00e9tude, le dernier volcan \u00e0 avoir g\u00e9n\u00e9r\u00e9 de telles\u2026","rel":"","context":"Dans &quot;Seismes\/Volcans&quot;","block_context":{"text":"Seismes\/Volcans","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/seismes-et-volcans\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/Hunga-Tonga-Hunga-Haapai-volcan-1.jpg?fit=990%2C660&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/Hunga-Tonga-Hunga-Haapai-volcan-1.jpg?fit=990%2C660&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/Hunga-Tonga-Hunga-Haapai-volcan-1.jpg?fit=990%2C660&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/Hunga-Tonga-Hunga-Haapai-volcan-1.jpg?fit=990%2C660&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":28169,"url":"https:\/\/www.laterredufutur.com\/accueil\/un-volcan-gigantesque-a-provoque-une-importante-eruption-liberant-du-methane-dans-latmosphere\/","url_meta":{"origin":24517,"position":5},"title":"Un volcan gigantesque a provoqu\u00e9 une importante \u00e9ruption, lib\u00e9rant du m\u00e9thane dans l&rsquo;atmosph\u00e8re","author":"Admin","date":"20 mai 2026","format":false,"excerpt":"Une \u00e9ruption volcanique cataclysmique est l'un des ph\u00e9nom\u00e8nes les plus violents et perturbateurs que notre plan\u00e8te puisse engendrer. D'immenses nuages \u200b\u200bde cendres et de gaz jaillissent dans l'atmosph\u00e8re, tandis que des roches en fusion br\u00fblantes remontent \u00e0 la surface et la recouvrent, d\u00e9truisant tout sur leur passage. Mais les volcans\u2026","rel":"","context":"Dans &quot;Seismes\/Volcans&quot;","block_context":{"text":"Seismes\/Volcans","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/seismes-et-volcans\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/explosion-volcanique-tonga.jpg?fit=1040%2C1120&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/explosion-volcanique-tonga.jpg?fit=1040%2C1120&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/explosion-volcanique-tonga.jpg?fit=1040%2C1120&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/explosion-volcanique-tonga.jpg?fit=1040%2C1120&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2022\/01\/explosion-volcanique-tonga.jpg?fit=1040%2C1120&ssl=1","_links":{"self":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/24517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/comments?post=24517"}],"version-history":[{"count":1,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/24517\/revisions"}],"predecessor-version":[{"id":24518,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/24517\/revisions\/24518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/media\/23642"}],"wp:attachment":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/media?parent=24517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/categories?post=24517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/tags?post=24517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}