{"id":20684,"date":"2020-03-20T08:00:37","date_gmt":"2020-03-20T07:00:37","guid":{"rendered":"https:\/\/www.laterredufutur.com\/accueil\/?p=20684"},"modified":"2020-03-19T15:56:04","modified_gmt":"2020-03-19T14:56:04","slug":"le-monde-change-et-si-les-changements-sociaux-avec-covid-19-seraient-un-prelude-a-une-vie-avec-moins-de-petrole","status":"publish","type":"post","link":"https:\/\/www.laterredufutur.com\/accueil\/le-monde-change-et-si-les-changements-sociaux-avec-covid-19-seraient-un-prelude-a-une-vie-avec-moins-de-petrole\/","title":{"rendered":"Le monde change, et si les changements sociaux avec COVID-19 seraient un pr\u00e9lude \u00e0 une vie avec moins de p\u00e9trole"},"content":{"rendered":"<div class=\"1665f18d14f35dd9e7566e1a8ac9a3e9\" data-index=\"1\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block; text-align:center;\"\r\n     data-ad-layout=\"in-article\"\r\n     data-ad-format=\"fluid\"\r\n     data-ad-client=\"ca-pub-2860849627502538\"\r\n     data-ad-slot=\"3019501113\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Alors que le monde essaie fi\u00e9vreusement de r\u00e9duire les \u00e9missions provenant de l&rsquo;utilisation de combustibles fossiles, nous sommes frapp\u00e9s par l&rsquo;horrible Coronavirus COVID-19 qui est tr\u00e8s contagieux. Nous avons assist\u00e9 \u00e0 d&rsquo;importants ajustements sociaux auto-impos\u00e9s des transports qui sont tr\u00e8s similaires \u00e0 ce qui sera n\u00e9cessaire pour vivre avec moins de combustibles fossiles \u00e0 l&rsquo;avenir.<\/p>\n<p>Nous avons constat\u00e9 une r\u00e9duction importante de l&rsquo;utilisation des infrastructures de transport des compagnies a\u00e9riennes et des navires de croisi\u00e8re, ainsi que des automobiles et des camions, et de leur impact sur les industries de loisirs et du divertissement, le tout pour \u00e9viter les foules.<\/p>\n<p>Avant les combustibles fossiles et les milliers de produits fabriqu\u00e9s \u00e0 partir de d\u00e9riv\u00e9s du p\u00e9trole et l&rsquo;\u00e9lectricit\u00e9 qui ont suivi, le monde \u00e9tait une fosse \u00e0 serpents avec un r\u00e9sultat nul qui \u00e9tait une guerre les uns contre les autres cherchant de la nourriture, de l&rsquo;eau et un abri. Dans les ann\u00e9es 1800, la plupart des gens n&rsquo;ont jamais voyag\u00e9 \u00e0 100-200 milles de leur lieu de naissance. L&rsquo;esp\u00e9rance de vie dans toute l&rsquo;Europe oscillait entre 20 et 30 ans.<\/p>\n<p>Les modes de vie sociaux avant 1900 n&rsquo;avaient pas un tels choix de transport, car ils n&rsquo;avaient pas d&rsquo;autos, d&rsquo;avions ou de bateaux de croisi\u00e8re pour le transport. Les inventions de l&rsquo;automobile, de l&rsquo;aviation et de l&rsquo;utilisation du p\u00e9trole au d\u00e9but des ann\u00e9es 1900 nous ont plong\u00e9s dans la r\u00e9volution industrielle. Le p\u00e9trole brut, le gaz naturel et le charbon ont chang\u00e9 &#8211; pour le mieux &#8211; les modes de vie de chaque personne vivant dans des pays d\u00e9velopp\u00e9s tels que les \u00c9tats-Unis, l&rsquo;Europe, le Japon, la Cor\u00e9e du Sud et l&rsquo;Australie.<\/p>\n<p>Nous ne serions pas en mesure de \u00abfabriquer des produits et de d\u00e9placer des choses\u00bb sans les milliers de produits d\u00e9riv\u00e9s du p\u00e9trole qui sont fabriqu\u00e9s \u00e0 partir de p\u00e9trole brut que les \u00e9oliennes et les panneaux solaires ne peuvent pas fabriquer. Certains de ces produits qui font partie des soci\u00e9t\u00e9s modernes comprennent:<\/p>\n<p>Les \u00e9conomies du monde entier et toutes les infrastructures augmentent chaque ann\u00e9e leur demande et leur utilisation de ces sources d&rsquo;\u00e9nergie \u00e0 partir de min\u00e9raux \/ combustibles de la terre profonde pour fabriquer des milliers de produits, y compris, mais sans s&rsquo;y limiter:<\/p>\n<p>\u00b7 M\u00e9dicaments et \u00e9quipement m\u00e9dical pour soigner la plupart des maladies<br \/>\n\u00b7 \u00c9lectronique pour les communications mondiales<br \/>\n\u00b7 Des engrais pour aider l&rsquo;agriculture \u00e0 nourrir le monde<br \/>\n\u00b7 Asphalte pour toutes les routes<br \/>\n\u00b7 Pneus pour tous les v\u00e9hicules<br \/>\n\u00b7 De l&rsquo;acier pour tous les b\u00e2timents du monde<br \/>\n\u00b7 C\u00e2ble pour le r\u00e9seau \u00e9lectrique mondial<\/p>\n<p>Aujourd&rsquo;hui, les compagnies a\u00e9riennes qui n&rsquo;existaient pas avant 1900, ont transport\u00e9 plus de 4,1 milliards de passagers en 2017 dans le monde et les projections sont de 7,8 milliards de passagers a\u00e9riens d&rsquo;ici 2036. Les navires de croisi\u00e8re qui n&rsquo;existaient pas avant 1900 d\u00e9placent 25 millions de passagers dans le monde chaque ann\u00e9e.<\/p>\n<p>Parall\u00e8lement \u00e0 ces options de transport disponibles pour la soci\u00e9t\u00e9, nous avons \u00e9galement des milliards de d\u00e9placements en v\u00e9hicule vers et depuis les a\u00e9roports, les h\u00f4tels, les ports et les parcs d&rsquo;attractions qui augmentent chaque ann\u00e9e. COVID-19 nous a montr\u00e9 que les changements de soci\u00e9t\u00e9 peuvent r\u00e9duire la demande de ces facteurs toujours plus croissants.<\/p>\n<p>Oui, nous utilisons peut-\u00eatre trop les combustibles fossiles pour les loisirs et le divertissement, mais le monde d\u00e9velopp\u00e9 est o\u00f9 il est aujourd&rsquo;hui, plus sain et plus riche, \u00e0 cause de tous les produits que nous obtenons de ces d\u00e9riv\u00e9s du p\u00e9trole.<\/p>\n<p>Pour atteindre ces objectifs de faibles \u00e9missions, nous devrons continuer \u00e0 r\u00e9duire les demandes de transport de la soci\u00e9t\u00e9 et COVID-19 pourrait nous montrer comment nous devrons nous retirer de notre utilisation extravagante des divers syst\u00e8mes de transport qui n&rsquo;existaient pas avant les carburants fossiles.<\/p>\n<p>Notre future existence pourrait \u00eatre moins de vacances et moins de conf\u00e9rences d&rsquo;affaires. Des r\u00e9ductions de l&rsquo;utilisation des industries du divertissement et de l&rsquo;h\u00f4tellerie, qui n&rsquo;existaient pas avant les combustibles fossiles, pourraient \u00e9galement \u00eatre n\u00e9cessaires.<\/p>\n<p>Alors que nous nous d\u00e9barrassons du p\u00e9trole, nous devrons r\u00e9duire nos demandes en infrastructures de transport que COVID-19 nous a montr\u00e9.<\/p>\n<p>Alors que nous nous \u00e9loignons des combustibles fossiles, nous devons accepter que de nombreux pays en d\u00e9veloppement comme de nombreux autres en Chine, en Inde et en Afrique qui sont encore coinc\u00e9s dans l&rsquo;\u00e8re d&rsquo;avant 1900 n&rsquo;ont pas encore rejoint la r\u00e9volution industrielle et l&rsquo;occasion de profiter des milliers de produits dans nos modes de vie quotidiens, ne le feront peut-\u00eatre jamais, car les carburants qui r\u00e9pondent aux demandes des diverses infrastructures de transport diminueront.<\/p>\n<p>Les politiciens qui s&rsquo;attaquent \u00e0 l&rsquo;industrie p\u00e9troli\u00e8re et gazi\u00e8re et cherchent \u00e0 sa disparition sont les m\u00eames qui r\u00e9coltent les b\u00e9n\u00e9fices des m\u00e9dicaments, de l&rsquo;\u00e9quipement m\u00e9dical, des r\u00e9seaux de communication et des milliers d&rsquo;autres produits de cette industrie qui ont contribu\u00e9 \u00e0 leur mode de vie et \u00e0 leur capacit\u00e9 \u00e0 vivre au-del\u00e0 de 80 ans. Ceux qui parlent d&rsquo;\u00e9missions doivent rejoindre le mouvement de conservation.<\/p>\n<p>Oui, le monde a chang\u00e9 par rapport aux soci\u00e9t\u00e9s qui existaient \u00e0 l&rsquo;\u00e9poque primitive, sans compagnies a\u00e9riennes, trains, v\u00e9hicules, navires marchands, m\u00e9dicaments, engrais, cosm\u00e9tiques et \u00e9quipements militaires tels que porte-avions, cuirass\u00e9s, avions, chars et armures, camions, porte-troupes, et des armes et de l&rsquo;\u00e9lectricit\u00e9 qui n&rsquo;existaient pas avant 1900, mais c&rsquo;est peut-\u00eatre le moment de commencer \u00e0 montrer nos cartes de conservation.<\/p>\n<p>\u00c0 un rythme rapide, de plus en plus de pays et de gouvernements d\u00e9placent leurs politiques \u00e9nerg\u00e9tiques pour d\u00e9barrasser le monde des combustibles fossiles afin d\u2019\u00e9lectrifier les soci\u00e9t\u00e9s en utilisant uniquement l\u2019\u00e9lectricit\u00e9 intermittente des \u00e9oliennes et des panneaux solaires. L&rsquo;\u00e9lectricit\u00e9 \u00e0 elle seule peut soutenir un mode de vie plus simple, mais ne peut pas r\u00e9pondre aux \u00e9normes besoins \u00e9nerg\u00e9tiques des infrastructures de transport, ni fournir les milliers de produits que les soci\u00e9t\u00e9s exigent de ces d\u00e9riv\u00e9s du p\u00e9trole.<\/p>\n<p>Alors que tout le monde am\u00e9liore sa conservation et son utilisation efficace de l&rsquo;\u00e9nergie, il peut \u00eatre opportun de commencer \u00e0 nous s\u00e9parer des infrastructures de transport et des industries des loisirs et du divertissement au mieux de leurs capacit\u00e9s pour conserver le p\u00e9trole l\u00e0 o\u00f9 il est le plus n\u00e9cessaire pour la soci\u00e9t\u00e9, les milliers de produits qui soutiennent les modes de vie ainsi que le d\u00e9veloppement \u00e9conomique mondial durable.<\/p>\n<p>Ronald Stein, PE. Fondateur et ambassadeur de l&rsquo;\u00e9nergie et des infrastructures. PTSadvance.com<\/p>\n<p>Adaptation <a href=\"https:\/\/www.laterredufutur.com\/accueil\/\" rel=\"noopener noreferrer\" target=\"_blank\">Terra Projects<\/a><\/p>\n<p>source : <a href=\"https:\/\/wattsupwiththat.com\/2020\/03\/12\/social-changes-with-covid-19-are-a-prelude-to-life-with-less-fossil-fuels\/\" rel=\"noopener noreferrer\" target=\"_blank\">https:\/\/wattsupwiththat.com\/<\/a><\/p>\n<p class=\"bawpvc-ajax-counter\" data-id=\"20684\">(446)<\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Alors que le monde essaie fi\u00e9vreusement de r\u00e9duire les \u00e9missions provenant de l&rsquo;utilisation de combustibles fossiles, nous sommes frapp\u00e9s par&#8230;<\/p>\n","protected":false},"author":1,"featured_media":20685,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Le #monde change, et si les changements sociaux avec #covid19COVID-19 seraient un pr\u00e9lude \u00e0 une vie avec moins de #p\u00e9trole @laterredufutur.com Terra Projects","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[7369,7368,1693,130,88,844],"class_list":["post-20684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-monde-futur","tag-coronavirus","tag-covid19","tag-energie-fossile","tag-monde","tag-petrole","tag-societe","wpcat-18-id"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2020\/03\/monde-covid19-interconnections.jpg?fit=1000%2C750&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p631RN-5nC","jetpack-related-posts":[{"id":17408,"url":"https:\/\/www.laterredufutur.com\/accueil\/2050-vers-un-monde-sans-carbone\/","url_meta":{"origin":20684,"position":0},"title":"2050 : vers un monde sans carbone ?","author":"Admin","date":"14 janvier 2019","format":false,"excerpt":"Afin de sauver le climat et par cons\u00e9quent la plan\u00e8te, l\u2019objectif fix\u00e9 par les directives de l\u2019IPCC, organisme onusien bien connu pour sa probit\u00e9 scientifique, est d\u2019atteindre en 2050 un taux d\u2019\u00e9missions de carbone \u00e9gal \u00e0 celui de l\u2019ann\u00e9e 1902. Au d\u00e9but du XXe si\u00e8cle l\u2019automobile en \u00e9tait \u00e0 ses\u2026","rel":"","context":"Dans &quot;Monde Futur&quot;","block_context":{"text":"Monde Futur","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/monde-futur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2018\/12\/paysant-debut-20em-si%C3%A8cle.jpg?fit=680%2C480&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2018\/12\/paysant-debut-20em-si%C3%A8cle.jpg?fit=680%2C480&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2018\/12\/paysant-debut-20em-si%C3%A8cle.jpg?fit=680%2C480&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":24421,"url":"https:\/\/www.laterredufutur.com\/accueil\/voici-la-quantite-de-combustible-fossile-sur-laquelle-le-monde-est-assis-et-cest-une-bombe-a-retardement\/","url_meta":{"origin":20684,"position":1},"title":"Voici la quantit\u00e9 de combustible fossile sur laquelle le monde est assis, et c&rsquo;est une bombe \u00e0 retardement","author":"Admin","date":"23 septembre 2022","format":false,"excerpt":"Br\u00fbler les r\u00e9serves mondiales restantes de combustibles fossiles lib\u00e9rerait 3,5 trillions de tonnes d'\u00e9missions de gaz \u00e0 effet de serre, soit sept fois le budget carbone restant pour limiter le r\u00e9chauffement de la plan\u00e8te \u00e0 1,5 degr\u00e9 Celsius, selon le premier inventaire public des hydrocarbures publi\u00e9 ce mois-ci. L'activit\u00e9 humaine\u2026","rel":"","context":"Dans &quot;Monde Futur&quot;","block_context":{"text":"Monde Futur","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/monde-futur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2021\/12\/petrole-pompage.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2021\/12\/petrole-pompage.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2021\/12\/petrole-pompage.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2021\/12\/petrole-pompage.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":25225,"url":"https:\/\/www.laterredufutur.com\/accueil\/le-monde-a-loree-du-debut-de-la-fin-de-lere-des-combustibles-fossiles\/","url_meta":{"origin":20684,"position":2},"title":"Le monde \u00e0 l&rsquo;or\u00e9e du \u00ab d\u00e9but de la fin \u00bb de l&rsquo;\u00e8re des combustibles fossiles","author":"Admin","date":"21 septembre 2023","format":false,"excerpt":"Pour la premi\u00e8re fois, la demande mondiale de p\u00e9trole, de gaz et de charbon devrait atteindre son maximum au cours de cette d\u00e9cennie en raison de la croissance \"spectaculaire\" des technologies \u00e9nerg\u00e9tiques plus propres et des voitures \u00e9lectriques, a d\u00e9clar\u00e9 mardi 12 septembre 2023 le directeur g\u00e9n\u00e9ral de l'Agence internationale\u2026","rel":"","context":"Dans &quot;Monde Futur&quot;","block_context":{"text":"Monde Futur","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/monde-futur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2021\/12\/petrole-pompage.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2021\/12\/petrole-pompage.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2021\/12\/petrole-pompage.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2021\/12\/petrole-pompage.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":822,"url":"https:\/\/www.laterredufutur.com\/accueil\/les-algues-notre-futur-plein-dessence\/","url_meta":{"origin":20684,"position":3},"title":"Les algues, notre futur plein d\u2019essence ?","author":"Admin","date":"25 mars 2012","format":false,"excerpt":"Les algues pourraient bient\u00f4t remplacer le p\u00e9trole pour faire rouler nos voitures. Elles ont l'avantage de rejeter beaucoup moins de CO2 que le p\u00e9trole et leur production est peu polluante. \u00c0 quand, le premier plein d'algues ? Et quand un p\u00e9trolier comme ExxonMobil se pr\u00e9pare au tournant... Il y a\u2026","rel":"","context":"Dans &quot;Solutions&quot;","block_context":{"text":"Solutions","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/solutions\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4536,"url":"https:\/\/www.laterredufutur.com\/accueil\/tour-du-monde-ecologique-de-lhy-bird\/","url_meta":{"origin":20684,"position":4},"title":"Tour du monde \u00e9cologique de l&rsquo;Hy-Bird","author":"Admin","date":"28 juillet 2008","format":false,"excerpt":"A partir de 2009, Hy-Bird sera le premier avion \u00e0 faire le tour du monde en utilisant uniquement des \u00e9nergies renouvelables, l\u2019\u00e9nergie solaire et l\u2019hydrog\u00e8ne. Ce tour du monde, par \u00e9tapes de 1500 kms, se veut \u00eatre un challenge \u00e0 la fois technologique et \u00e9cologique mais aussi humain. Contexte du\u2026","rel":"","context":"Dans &quot;Solutions&quot;","block_context":{"text":"Solutions","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/solutions\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2938,"url":"https:\/\/www.laterredufutur.com\/accueil\/demain-une-nouvelle-energie\/","url_meta":{"origin":20684,"position":5},"title":"Hydrates de m\u00e9thane : cette \u00ab glace combustible \u00bb qui pourrait transformer l&rsquo;avenir de l&rsquo;\u00e9nergi","author":"Admin","date":"10 juin 2005","format":false,"excerpt":"Alors que les r\u00e9serves de p\u00e9trole conventionnel deviennent plus difficiles \u00e0 exploiter et que la transition \u00e9nerg\u00e9tique s'acc\u00e9l\u00e8re, une ressource enfouie depuis des millions d'ann\u00e9es sous les oc\u00e9ans suscite un int\u00e9r\u00eat croissant : les hydrates de m\u00e9thane. Longtemps consid\u00e9r\u00e9s comme une curiosit\u00e9 g\u00e9ologique, ces cristaux de glace renfermant du gaz\u2026","rel":"","context":"Dans &quot;Solutions&quot;","block_context":{"text":"Solutions","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/solutions\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2005\/06\/Hydrates-de-methane.png?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2005\/06\/Hydrates-de-methane.png?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2005\/06\/Hydrates-de-methane.png?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2005\/06\/Hydrates-de-methane.png?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2005\/06\/Hydrates-de-methane.png?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/20684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/comments?post=20684"}],"version-history":[{"count":1,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/20684\/revisions"}],"predecessor-version":[{"id":20686,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/20684\/revisions\/20686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/media\/20685"}],"wp:attachment":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/media?parent=20684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/categories?post=20684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/tags?post=20684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}