{"id":11749,"date":"2016-04-11T12:09:50","date_gmt":"2016-04-11T11:09:50","guid":{"rendered":"http:\/\/www.laterredufutur.com\/accueil\/?p=11749"},"modified":"2026-06-08T11:26:21","modified_gmt":"2026-06-08T11:26:21","slug":"le-japon-va-construire-un-mur-de-glace-pour-decontaminer-fukushima","status":"publish","type":"post","link":"https:\/\/www.laterredufutur.com\/accueil\/le-japon-va-construire-un-mur-de-glace-pour-decontaminer-fukushima\/","title":{"rendered":"Le Japon va construire un mur de glace pour d\u00e9contaminer Fukushima"},"content":{"rendered":"<div class=\"1665f18d14f35dd9e7566e1a8ac9a3e9\" data-index=\"1\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block; text-align:center;\"\r\n     data-ad-layout=\"in-article\"\r\n     data-ad-format=\"fluid\"\r\n     data-ad-client=\"ca-pub-2860849627502538\"\r\n     data-ad-slot=\"3019501113\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p style=\"text-align: justify;\">En 2011, le\u00a0tsunami qui a \u00e9t\u00e9 provoqu\u00e9\u00a0par le\u00a0tremblement de terre a frapp\u00e9 la centrale de Fukushima au Japon et a fini par causer un accident nucl\u00e9aire majeur.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;accident a \u00e9t\u00e9 consid\u00e9r\u00e9 comme la plus grande catastrophe naturelle depuis l&rsquo;accident nucl\u00e9aire de Tchernobyl. Et malheureusement, l&rsquo;accident a lib\u00e9r\u00e9\u00a0un flux catastrophique de radioactivit\u00e9s\u00a0et de rayonnement dans l&rsquo;eau de mer.<\/p>\n<p style=\"text-align: justify;\">Les japonais\u00a0ont fait\u00a0des tentatives pour \u00e9liminer les mati\u00e8res radioactives de toute la zone, mais les temp\u00e9ratures \u00e9lev\u00e9es et la radioactivit\u00e9 donne une id\u00e9e de la grande probl\u00e9matique.<\/p>\n<p style=\"text-align: justify;\">Ainsi, les Japonais ont d\u00e9cid\u00e9 de cr\u00e9er un mur de glace pour mettre fin au probl\u00e8me!<\/p>\n<p style=\"text-align: justify;\">Pour comprendre la solution, vous aurez besoin de comprendre comment ils ont travaill\u00e9.<\/p>\n<p style=\"text-align: justify;\">La centrale de Fukushima produit de l&rsquo;\u00e9nergie avec une s\u00e9rie de r\u00e9acteurs qui ont \u00e9t\u00e9 mis en contact avec des tonnes d&rsquo;eau. Ainsi, le liquide s&rsquo;\u00e9vapore et les turbines \u00e0 vapeur vont \u00eatre d\u00e9plac\u00e9es pour\u00a0produire de l&rsquo;\u00e9nergie.<\/p>\n<p style=\"text-align: justify;\">Le projet japonais est d&rsquo;utiliser des tubes frigorifiques situ\u00e9es \u00e0 30 m\u00e8tres de profondeur. Une fois connect\u00e9s, ces tuyaux vont cr\u00e9er une barri\u00e8re de glace (d&rsquo;environ 1,5 km de long) pour entourer toute la zone nucl\u00e9aire.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;ensemble de ce projet co\u00fbtera autour de $ 1 milliard. Et, croyez-le ou non, dans le cas d&rsquo;un grand projet ceci reste\u00a0une valeur faible co\u00fbt.<\/p>\n<p style=\"text-align: justify;\">Ci-dessous vous pouvez voir une vid\u00e9o sur le sujet:<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/-jyg5PYOcEA?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p>Le Japon va construire un mur de glace pour d\u00e9contaminer Fukushima<\/p>\n<p>Traduction et adaptation de <a href=\"https:\/\/www.laterredufutur.com\/accueil\/\">la Terre du Futur<\/a><\/p>\n<p>&nbsp;<\/p>\n<p class=\"bawpvc-ajax-counter\" data-id=\"11749\">(687)<\/p>\n<!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>En 2011, le\u00a0tsunami qui a \u00e9t\u00e9 provoqu\u00e9\u00a0par le\u00a0tremblement de terre a frapp\u00e9 la centrale de Fukushima au Japon et a&#8230;<\/p>\n","protected":false},"author":1,"featured_media":11750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Le #Japon va construire un mur de glace pour d\u00e9contaminer #Fukushima @laterredufutur","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[28,26],"tags":[5739,101,335,267,107,5738,310,100,684],"class_list":["post-11749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pollution","category-solutions","tag-decontaminer","tag-energie","tag-fukushima","tag-glace","tag-japon","tag-mur-de-glace","tag-radioactivite","tag-solution","tag-video","wpcat-28-id","wpcat-26-id"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2016\/04\/mur-glace-fukushima.png?fit=700%2C375&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p631RN-33v","jetpack-related-posts":[{"id":5732,"url":"https:\/\/www.laterredufutur.com\/accueil\/catastrophe-nucleaire-au-japon\/","url_meta":{"origin":11749,"position":0},"title":"Catastrophe Nucl\u00e9aire au Japon","author":"Admin","date":"15 mars 2011","format":false,"excerpt":"Une explosion a endommag\u00e9 l'enceinte de confinement du r\u00e9acteur 2 de la centrale de Fukushima Mardi 15 mars 2011 : 8h38: Le risque nucl\u00e9aire est \"extr\u00eamement \u00e9lev\u00e9\" au Japon, a d\u00e9clar\u00e9 mardi le chef de la diplomatie fran\u00e7aise Alain Jupp\u00e9, apr\u00e8s une discussion avec son homologue nippon au sein du\u2026","rel":"","context":"Dans &quot;Ev\u00e8nement Brutal&quot;","block_context":{"text":"Ev\u00e8nement Brutal","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/evenement-brutal\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2015\/04\/le-japon-menace-par-un-accident-nucleaire.jpeg?fit=480%2C329&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1039,"url":"https:\/\/www.laterredufutur.com\/accueil\/un-nouveau-futur-cataclysme-au-japon\/","url_meta":{"origin":11749,"position":1},"title":"Un nouveau futur cataclysme au Japon ?","author":"Admin","date":"9 septembre 2012","format":false,"excerpt":"Depuis le tsunami du 11 mars 2011, le Japon a connu le pire cataclysme de l'\u00e9poque moderne. Et si ce n'\u00e9tait pas le dernier ? Cette fois-ci, cela serait tout autre chose. Fukushima montre des signes inqui\u00e9tants que m\u00eame l'ensemble des m\u00e9dias fran\u00e7ais en font l'\u00e9chos. C'est une petite piscine\u2026","rel":"","context":"Dans &quot;Pollution&quot;","block_context":{"text":"Pollution","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/pollution\/"},"img":{"alt_text":"fukushima","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/wordpress\/wp-content\/uploads\/2012\/09\/fukushima-radioactivite.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":12889,"url":"https:\/\/www.laterredufutur.com\/accueil\/fukushima-le-niveau-de-radioactivite-serait-en-forte-baisse-dans-locean-pacifique\/","url_meta":{"origin":11749,"position":2},"title":"Fukushima : le niveau de radioactivit\u00e9 serait en forte baisse dans l&rsquo;oc\u00e9an pacifique ?","author":"Admin","date":"17 juillet 2016","format":false,"excerpt":"Selon une \u00e9tude internationale publi\u00e9e d\u00e9but juillet 2016, le niveau de radioactivit\u00e9 dans l'oc\u00e9an Pacifique a largement diminu\u00e9, cinq ans apr\u00e8s la catastrophe nucl\u00e9aire de Fukushima. Mais les zones les plus proches de la centrale restent encore tr\u00e8s contamin\u00e9es. Les niveaux de radioactivit\u00e9 \u00e0 travers l'oc\u00e9an Pacifique seraient en train\u2026","rel":"","context":"Dans &quot;Pollution&quot;","block_context":{"text":"Pollution","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/pollution\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18559,"url":"https:\/\/www.laterredufutur.com\/accueil\/le-11-mars-2011-avait-lieu-une-catastrophe-epouvantable-au-japon-ou-en-sommes-nous\/","url_meta":{"origin":11749,"position":3},"title":"Le 11 mars 2011 avait lieu une catastrophe \u00e9pouvantable au Japon, o\u00f9 en sommes nous ?","author":"Admin","date":"11 mars 2019","format":false,"excerpt":"Le Japon comm\u00e9more la catastrophe de Fukushima, le tremblement de terre puis le tsunami et l'accident nucl\u00e9aire qui, il y a huit ans jour pour jour, le 11 mars 2011, ont fait 18 000 morts et disparus. Ce drame a rendu les Japonais encore plus attentifs au risque de catastrophes\u2026","rel":"","context":"Dans &quot;Ev\u00e8nement Brutal&quot;","block_context":{"text":"Ev\u00e8nement Brutal","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/evenement-brutal\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2019\/03\/tsunami-japon-8.jpg?fit=820%2C547&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2019\/03\/tsunami-japon-8.jpg?fit=820%2C547&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2019\/03\/tsunami-japon-8.jpg?fit=820%2C547&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2019\/03\/tsunami-japon-8.jpg?fit=820%2C547&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1109,"url":"https:\/\/www.laterredufutur.com\/accueil\/fukushima-la-strategie-de-loubli\/","url_meta":{"origin":11749,"position":4},"title":"Fukushima, la strat\u00e9gie de l\u2019oubli","author":"Admin","date":"6 novembre 2012","format":false,"excerpt":"Un livre vient de sortir, \u00ab oublier Fukushima \u00a0\u00bb (\u00e9ditions du bout de la ville), faisant un bilan saisissant, d\u00e9cryptant les man\u0153uvres subtiles de communication de Tepco et de l\u2019Etat Japonais, qui tentent de faire oublier la catastrophe toujours en cours, pourtant un incendie a eu lieu le 20 octobre\u2026","rel":"","context":"Dans &quot;Pollution&quot;","block_context":{"text":"Pollution","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/pollution\/"},"img":{"alt_text":"fujushima","src":"https:\/\/i0.wp.com\/www.laterredufutur.com\/accueil\/wp-content\/uploads\/2012\/09\/fukushima-explosion.jpg?fit=480%2C270&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":835,"url":"https:\/\/www.laterredufutur.com\/accueil\/des-tonnes-deau-radioactive-ont-fui-de-la-centrale-de-fukushima\/","url_meta":{"origin":11749,"position":5},"title":"Des tonnes d&rsquo;eau radioactive ont fui de la centrale de Fukushima","author":"Admin","date":"5 avril 2012","format":false,"excerpt":"Jeudi, la compagnie Tepco, op\u00e9rateur de la centrale accident\u00e9e de Fukushima, a annonc\u00e9 que quelque 12 tonnes d'eau avaient fui de l'installation. Une partie du liquide pourrait s'\u00eatre \u00e9coul\u00e9e dans l'oc\u00e9an. Alors que l'accident d\u00e9but\u00e9 en mars 2011 est aujourd'hui consid\u00e9r\u00e9 comme termin\u00e9, les difficult\u00e9s sont loin d'avoir totalement disparues\u2026","rel":"","context":"Dans &quot;Pollution&quot;","block_context":{"text":"Pollution","link":"https:\/\/www.laterredufutur.com\/accueil\/sujets\/pollution\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/11749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/comments?post=11749"}],"version-history":[{"count":1,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/11749\/revisions"}],"predecessor-version":[{"id":11751,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/posts\/11749\/revisions\/11751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/media\/11750"}],"wp:attachment":[{"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/media?parent=11749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/categories?post=11749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laterredufutur.com\/accueil\/wp-json\/wp\/v2\/tags?post=11749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}